{"id":137265,"date":"2020-09-25T08:22:24","date_gmt":"2020-09-25T06:22:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-cedole-scuola-primaria-2019-non-pagate-si-cerca-una-soluzione\/"},"modified":"2023-01-16T18:07:12","modified_gmt":"2023-01-16T17:07:12","slug":"373240-cosenza-cedole-scuola-primaria-2019-non-pagate-si-cerca-una-soluzione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/373240-cosenza-cedole-scuola-primaria-2019-non-pagate-si-cerca-una-soluzione\/","title":{"rendered":"Cosenza: cedole scuola primaria 2019 non pagate, si cerca una soluzione"},"content":{"rendered":"<h4>Il Comune ha inserito i 119 mila euro che avanzano i librai per i testi distribuiti nel 2019 nel dissesto finanziario. I librai a causa del mancato incasso del credito non possono acquistare i testi dalle case editrici per l&#8217;anno scolastico in corso<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Il Comune non ha pagato i buoni libro del 2018\/2019, somma che si aggira intorno ai 110 mila euro, finita nel calderone del dissesto finanziario. La scuola \u00e8 appena iniziata e i ragazzi delle scuole primarie (elementari) dovrebbero ricevere i nuovi testi scolastici, ma i librai sono in difficolt\u00e0 perch\u00e9 non hanno ancora saldato gli editori per la fornitura dello scorso anno. <strong>A denunciare la situazione \u00e8 Gennaro Sauzullo, uno dei quattro librai di Cosenza che non ha ancora ottenuto il saldo della fornitura.<\/strong> &#8220;Ad oggi nessun pagamento e chiediamo l&#8217;intervento immediato &#8211; ha spiegato Sauzullo a nome anche dei colleghi &#8211; del sindaco e dell&#8217;amministrazione tutta, perch\u00e8 noi attendiamo il pagamento delle nostre spettanze, non chiediamo aiuti o finanziamenti a fondo perduto ma semplicemente il pagamento dei nostri crediti&#8221;.<\/p>\n<p><strong>Gennaro Sauzullo<\/strong> ha illustrato i contorni della vicenda ai microfoni di <strong>Rlb<\/strong><\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA<\/span><br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/899277772&amp;color=%23ff5500&amp;auto_play=true&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/h4>\n<div style=\"font-size: 10px; color: #cccccc; line-break: anywhere; word-break: normal; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; font-family: Interstate,Lucida Grande,Lucida Sans Unicode,Lucida Sans,Garuda,Verdana,Tahoma,sans-serif; font-weight: 100;\"><a style=\"color: #cccccc; text-decoration: none;\" title=\"QuiCosenza.it\" href=\"https:\/\/quicosenza.it\/news\/10087\" target=\"_blank\" rel=\"noopener noreferrer\">QuiCosenza.it<\/a> \u00b7 <a style=\"color: #cccccc; text-decoration: none;\" title=\"Gennaro Sauzullo - Libraio Cosenza\" href=\"https:\/\/quicosenza.it\/news\/11360\" target=\"_blank\" rel=\"noopener noreferrer\">Gennaro Sauzullo &#8211; Libraio Cosenza<\/a><\/div>\n<p>&nbsp;<\/p>\n<p><strong>Il credito vantato dai librai per la fornitura dei libri per la scuola elementare ammonta a 119.150,00. &#8220;<\/strong>Il Comune &#8211; ha poi aggiunto Sauzullo &#8211; dichiara che le nostre spettanze sono soldi provenienti dal bilancio comunale, e pertanto sono andati nel dissesto, senza tener conto che abbiamo fornito libri con il prezzo calmierato imposto dal ministero e non a caso dietro la copertina c\u2019e\u2019 scritto prezzo ministeriale, inoltre libri che noi librerie acquistiamo con lo sconto del 16%&#8221;.<\/p>\n<p>&#8220;Il Comune &#8211; ha continuato Sauzullo &#8211; ha liquidato tutte le librerie che vendono libri di scuola media e superiori che non siamo noi, per un importo di circa 450.000,00 e il sindaco tramite Facebook dichiara che per l\u2019anno 2020 non ci sono problemi per acquistare i testi per le scuole primarie. Allo stato per\u00f2 noi non abbiamo ancora ricevuto il dovuto&#8221;. <strong>Diversi gli incontri tra i librai, la dirigente del settore Educazione del Comune e l\u2019assessore alla Cultura, Matilde Spadafora<\/strong>, durante i quali sono emerse le difficolt\u00e0 nel acquistare dalle case editrici i nuovi testi scolastici perch\u00e8 ancora sono stati saldati i debiti riferiti ai testi consegnati per il 2019.<\/p>\n<p>&#8220;Ci sarebbe una soluzione\u00a0 &#8211; ha infine concluso Sauzullo &#8211; che abbiamo proposto all&#8217;assessore Spadafora, che fa riferimento all&#8217;art. 250 del Testo unico degli enti locali che consente di non far rientrare queste somme nel dissesto e prevede la possibilit\u00e0 per il Consiglio di deliberare il pagamento di queste somme&#8221;. <strong>Si attende un nuovo incontro tra le parti, nei prossimi giorni,<\/strong> sperando che si arrivi ad una soluzione definitiva e al pagamento delle spettanze.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune ha inserito i 119 mila euro che avanzano i librai per i testi distribuiti nel 2019 nel dissesto finanziario. I librai a causa del mancato incasso del credito non possono acquistare i testi dalle case editrici per l&#8217;anno scolastico in corso<\/p>\n","protected":false},"author":56,"featured_media":137266,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-137265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/137265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=137265"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/137265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/137266"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=137265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=137265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=137265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}