{"id":137521,"date":"2020-09-30T12:23:46","date_gmt":"2020-09-30T10:23:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/migranti-positivi-da-amantea-a-gasperina-protesta-dei-cittadini-trasferimento-sospeso\/"},"modified":"2023-01-16T18:07:29","modified_gmt":"2023-01-16T17:07:29","slug":"373958-migranti-positivi-da-amantea-a-gasperina-protesta-dei-cittadini-trasferimento-sospeso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/373958-migranti-positivi-da-amantea-a-gasperina-protesta-dei-cittadini-trasferimento-sospeso\/","title":{"rendered":"Migranti positivi da Amantea a Gasperina, protesta dei cittadini. Trasferimento sospeso"},"content":{"rendered":"<h4>Gli abitanti del centro catanzarese erano scesi in piazza per protestare contro il paventato trasferimenti dei migranti positivi in un albergo in disuso<br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>GASPERINA (CZ) &#8211; \u00c8 stato sospeso il trasferimento di un gruppo di migranti positivi al coronavirus da Amantea\u00a0 a Gasperina dopo la protesta questa mattina di un gruppo di residenti preoccupati per la mancanza delle condizioni di sicurezza nell&#8217;albergo in disuso in contrada Pilinga che avrebbe dovuto ospitare i migranti.<\/p>\n<p>L\u2019arrivo dei migranti dunque resta sospeso in attesa di chiarimenti, e intanto anche la protesta \u00e8 terminata. Stamattina erano scesi in strada alcuni cittadini del centro catanzarese contro l&#8217;ipotesi del trasferimento di una trentina di migranti positivi al Covid 19 da Amantea nel loro comune. Ad Amantea il focolaio di migranti preoccupa e nei giorni scorsi la stessa Asp di Cosenza aveva annunciato la necessit\u00e0 di dividere in strutture diverse i positivi dai negativi.\u00a0 Secondo i residenti di Gasperina per\u00f2, la struttura \u00e8 a pochi metri dalla chiesa, da una scuola materna, e non \u00e8 un posto isolato perch\u00e8 limitrofa alle case: &#8220;Vogliamo che ci venga assicurato il rispetto delle norme&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli abitanti del centro catanzarese erano scesi in piazza per protestare contro il paventato trasferimenti dei migranti positivi in un albergo in disuso<\/p>\n","protected":false},"author":42,"featured_media":137522,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-137521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/137521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=137521"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/137521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/137522"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=137521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=137521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=137521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}