{"id":138076,"date":"2020-10-09T10:26:59","date_gmt":"2020-10-09T08:26:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sequestro-in-due-macellerie-a-san-benedetto-ullano-carne-scaduta-e-non-tracciata\/"},"modified":"2023-01-16T18:08:07","modified_gmt":"2023-01-16T17:08:07","slug":"375366-sequestro-in-due-macellerie-a-san-benedetto-ullano-carne-scaduta-e-non-tracciata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/375366-sequestro-in-due-macellerie-a-san-benedetto-ullano-carne-scaduta-e-non-tracciata\/","title":{"rendered":"Sequestro in due macellerie a San Benedetto Ullano, carne scaduta e non tracciata"},"content":{"rendered":"<h4>I carabinieri forestali di Montalto Uffugo nell\u2019ambito di una attivit\u00e0 rivolta a controlli nel settore agroalimentare hanno sequestrato diversi chilogrammi di carne<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SAN BENEDETTO ULLANO (CS) &#8211; Controlli in due macellerie di San Benedetto Ullano, dei carabinieri forestali, al fine di assicurare il rispetto della tracciabilit\u00e0 e della rintracciabilit\u00e0 dei prodotti alimentari immessi nel mercato e del rispetto delle norme igienico-sanitarie. In una delle attivit\u00e0 ispezionate, sono state rinvenute svariate confezioni di <strong>carne avicola, oltre 10 chili, gi\u00e0 preimballate priva di alcuna indicazione<\/strong>, posta in <strong>vendita oltre la data di scadenza.<\/strong> Al titolare dunque, oltre al sequestro degli alimenti, sono state contestate le relative violazioni amministrative per un importo complessivo di oltre 3400 euro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-375368 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/10\/carne-sequestro-02.jpg\" alt=\"\" width=\"511\" height=\"428\" title=\"\"><\/p>\n<p>Nel corso di un ulteriore controllo in un&#8217;altra macelleria, i militari hanno sottoposto a sequestro amministrativo <strong>19 confezioni termo saldate in regime di sottovuoto di insaccati<\/strong> messi all\u2019interno del banco espositore refrigerato, pronti per essere immessi sul mercato al dettaglio, privi di qualsiasi indicazione necessaria: tipologia di carne, data di confezionamento, data di preparazione, scadenza e lotto. Anche in questo caso al titolare dell\u2019esercizio commerciale \u00e8 stata contestata una <strong>violazione amministrativa di 1500 euro. <\/strong>Tutta la merce \u00e8 stata sottoposta a sequestro cautelativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri forestali di Montalto Uffugo nell\u2019ambito di una attivit\u00e0 rivolta a controlli nel settore agroalimentare hanno sequestrato diversi chilogrammi di carne<\/p>\n","protected":false},"author":42,"featured_media":138077,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-138076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=138076"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/138077"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=138076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=138076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=138076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}