{"id":138198,"date":"2020-10-12T09:12:40","date_gmt":"2020-10-12T07:12:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/belvedere-marittimo-cede-il-muro-adiacente-la-strada-per-il-maltempo\/"},"modified":"2023-01-16T18:08:15","modified_gmt":"2023-01-16T17:08:15","slug":"375739-belvedere-marittimo-cede-il-muro-adiacente-la-strada-per-il-maltempo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/375739-belvedere-marittimo-cede-il-muro-adiacente-la-strada-per-il-maltempo\/","title":{"rendered":"Belvedere Marittimo: cede il muro adiacente la strada per il maltempo"},"content":{"rendered":"<h4>Il cedimento sarebbe stato causato dal maltempo che nelle ultime ore si \u00e8 abbattuto sulla costa tirrenica. La strada era gi\u00e0 chiusa per lavori proprio sul muro di contenimento<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>BELVEDERE MARITTIMO (CS) &#8211; Il muro di contenimento di una strada, in localit\u00e0 Vetticello di Belvedere \u00e8 stato interessato questa mattina da un cedimento legato allo smottamento della carreggiata. Sul posto i vigili del fuoco di Cosenza e del distaccamento di Scalea in quanto il crollo ha causato la rottura della condotta del gas metano. Sul posto anche la polizia locale, i tecnici comunali e quelli dell\u2019Italgas per il ripristino della rete di distribuzione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-375741 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/10\/Belvedere-muro-crollo-strada-02.jpeg\" alt=\"\" width=\"588\" height=\"807\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il cedimento sarebbe stato causato dal maltempo che nelle ultime ore si \u00e8 abbattuto sulla costa tirrenica. La strada era gi\u00e0 chiusa per lavori proprio sul muro di contenimento<\/p>\n","protected":false},"author":42,"featured_media":138199,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-138198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=138198"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138198\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/138199"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=138198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=138198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=138198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}