{"id":138226,"date":"2020-10-12T16:00:27","date_gmt":"2020-10-12T14:00:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/unical-smart-campus-nuove-funzioni-con-intelligenza-artificiale\/"},"modified":"2023-01-16T18:08:17","modified_gmt":"2023-01-16T17:08:17","slug":"375789-unical-smart-campus-nuove-funzioni-con-intelligenza-artificiale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/375789-unical-smart-campus-nuove-funzioni-con-intelligenza-artificiale\/","title":{"rendered":"Unical, Smart Campus: nuove funzioni con Intelligenza Artificiale"},"content":{"rendered":"<h4>Tracciamento degli studenti in caso di emergenza Covid, semaforo per le mense e registrazione presenze anche per chi segue a distanza<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ARCAVACATA (CS) &#8211; Nuove funzionalit\u00e0 per l\u2019app Smart Campus, che dopo la prima settimana di rodaggio, con ottimi risultati, si appresta a fornire <strong>nuovi strumenti potenziati da tecnologie di Intelligenza Artificiale<\/strong>, utili per gli studenti dell\u2019Universit\u00e0 della Calabria. Le due aziende spin-off dell\u2019Unical, CalTek e SOMOS, con la collaborazione dello spin-off universitario DLVSystem, finalizzata all\u2019implementazione del modulo per la <strong>ricostruzione della catena dei contagi,<\/strong> stanno lavorando per rendere ancora pi\u00f9 funzionale lo strumento, nato per l\u2019esigenza di monitorare le presenze in aula, nell\u2019ambito del programma Unical vs Covid voluto dal rettore Nicola Leone.<\/p>\n<p>I numeri della prima settimana di utilizzo sono significativi: si sono tenute<strong> 1084 lezioni che hanno fatto registrare 24.265 presenze. <\/strong>Il meccanismo delle prenotazioni, implementato con SmartCampus, ha funzionato alla perfezione e solo in <strong>14 casi su 1084 si \u00e8 saturata la capienza dell&#8217;aula<\/strong> (appena l\u2019uno per cento). Quindi l&#8217;Unical ha ospitato praticamente tutti gli studenti che hanno richiesto di seguire la lezione in aula, tranne poche unit\u00e0, informate sin dal giorno precedente, ma che hanno potuto comunque seguire online la lezione trasmessa in diretta dall&#8217;aula. Circa<strong> quattromila i pasti fruiti a mensa<\/strong> nella prima settimana di riapertura, senza registrare assembramenti grazie all&#8217;apertura di 3 sale distribuite nel Campus.<\/p>\n<p><strong>Registro presenze<\/strong><\/p>\n<p>Una nuova funzionalit\u00e0 gi\u00e0 rilasciata sulla web app (smartcampus.unical.it), ma che a giorni sar\u00e0 disponibile anche in versione mobile, \u00e8 quella della segnalazione della <strong>presenza a lezione anche per gli studenti che seguono a distanza.<\/strong> Registrare la propria presenza a lezione \u00e8 semplice: basta collegarsi sull\u2019app ad inizio lezione, selezionare l\u2019insegnamento che si sta per seguire e premere il tasto <strong>\u201cregistra presenza\u201d<\/strong>. In questo modo tutti gli studenti saranno correttamente inseriti nel registro elettronico delle presenze del corso che sar\u00e0 messo a disposizione del docente.<\/p>\n<p><strong>Tracciamento<\/strong><\/p>\n<p>Grazie al contributo dello spin-off universitario DLVSystem S.r.l., all\u2019avanguardia nella tecnologia di Intelligenza Artificiale, Smart Campus \u00e8 stata potenziata con nuovi importanti aggiornamenti: il primo \u00e8 uno strumento di <strong>tracciamento interno all\u2019Unical che permetter\u00e0, nel malaugurato caso in cui uno studente risulti positivo, di analizzare lo storico degli accessi registrati nel campus<\/strong> e creare un elenco delle persone con cui \u00e8 stato in contatto nelle due settimane precedenti. Non solo. Usando tecniche di advanced analytics, l\u2019app sar\u00e0 in grado di elaborare ulteriori dati come la frequenza con cui la persona \u00e8 stata a contatto con un\u2019altra, l\u2019ampiezza dello spazio fisico, la durata del contatto. In questo modo sar\u00e0 possibile <strong>ricostruire la catena del contagio<\/strong> non solo numerica, ma anche delle probabilit\u00e0 che una persona sia stata in maniera maggiore o minore esposta al contagio. La lista avr\u00e0 quindi un indice di priorit\u00e0, che, tramite il referente Covid dell\u2019Unical, sar\u00e0 fornito all&#8217;ASP, per procedere a contattare le persone interessate Per lo sviluppo del modulo relativo alla catena dei contagi DLVSystem si \u00e8 avvalsa del motore di AI per il ragionamento automatico, DLV, ingegnerizzato dallo spin off. Le attivit\u00e0 sono state coordinate dal responsabile tecnico di DLVSystem <strong>Giovanni Laboccetta<\/strong> e l\u2019implementazione \u00e8 stata effettuata da un team di esperti che sta curando anche l\u2019integrazione con l\u2019app Smart Campus.<\/p>\n<p><strong>Semaforo mensa<\/strong><\/p>\n<p>Altra novit\u00e0 in fase di rilascio riguarda l\u2019accesso alle mense. <strong>Per evitare assembramenti e file<\/strong>, l\u2019app sar\u00e0 presto dotata di una sezione \u201cmensa\u201d all\u2019interno della quale saranno presenti per ciascuna mensa un semaforo: il rosso indicher\u00e0 che la sala \u00e8 piena e i tempi di attesa sono molto lunghi, il giallo che la sala \u00e8 quasi piena ma il flusso di ingresso \u00e8 rapido, il verde che si pu\u00f2 entrare senza fila. <strong>Una volta arrivati nella mensa, si registrer\u00e0 la presenza<\/strong> con il Qr code (come gi\u00e0 avviene) ed \u00e8 allo studio anche la possibilit\u00e0 di utilizzare l\u2019app per il pagamento del pasto, al posto del tesserino.<\/p>\n<p><strong>Biblioteche e centri sportivi<\/strong><\/p>\n<p>Smart Campus sar\u00e0 attrezzata, in futuro, per consentire la prenotazione del prestito di un libro e fissare un appuntamento per il ritiro. Nel frattempo, saranno presto disponibili le funzioni per il tracciamento delle presenze nelle biblioteche e nei centri sportivi.<\/p>\n<p><strong>Segnalazioni<\/strong><\/p>\n<p>Per ogni esigenza o problema, gli sviluppatori hanno predisposto due mail dedicate: per problemi tecnici sulla versione mobile smartcampus@somos.srl , per problemi tecnici sulla versione web smartcampus@cal-tek.eu . Inoltre, \u00e8 in via di formazione un gruppo di utenti tester volontari, a titolo gratuito, che possano fornire le loro impressioni e indicazioni per lo sviluppo degli aggiornamenti, per aderire \u00e8 possibile scrivere una mail al professor Francesco Longo f.longo@unical.it .<\/p>\n<p>\u201cInvito gli studenti e i docenti \u2013 raccomanda il rettore <strong>Nicola Leone<\/strong> \u2013 ad aggiornare con regolarit\u00e0 l\u2019app \u201cSmart Campus\u201d, affinch\u00e9 questo strumento risulti pienamente efficace. \u00c8 importante che ognuno lo utilizzi insieme all\u2019app Immuni, che invito a <strong>scaricare per chi non avesse ancora provveduto, per rendere il pi\u00f9 possibile sicura la vita nel Campus.<\/strong> Solo con la partecipazione attiva e responsabile di tutti, la vita universitaria potr\u00e0 riprendere in tranquillit\u00e0, evitando il crearsi di assembramenti, utilizzando le mascherine sia nelle aule che all\u2019aperto e osservando quanto previsto dalle norme ministeriali. Sono piccoli sacrifici che tutti noi dobbiamo sostenere, a tutela della nostra salute e di quella delle persone che frequentiamo, anche al di fuori dell\u2019Unical\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tracciamento degli studenti in caso di emergenza Covid, semaforo per le mense e registrazione presenze anche per chi segue a distanza<\/p>\n","protected":false},"author":22,"featured_media":138227,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-138226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=138226"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/138227"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=138226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=138226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=138226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}