{"id":138312,"date":"2020-10-13T14:58:25","date_gmt":"2020-10-13T12:58:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/protesta-a-fuscaldo-di-alcuni-migranti-che-bloccano-la-statale-18\/"},"modified":"2023-01-16T18:08:22","modified_gmt":"2023-01-16T17:08:22","slug":"376005-protesta-a-fuscaldo-di-alcuni-migranti-che-bloccano-la-statale-18","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/376005-protesta-a-fuscaldo-di-alcuni-migranti-che-bloccano-la-statale-18\/","title":{"rendered":"Protesta a Fuscaldo di alcuni migranti che bloccano la statale 18"},"content":{"rendered":"<h4>Alcuni migranti ospiti del Cas di Fuscaldo hanno bloccato per alcuni minuti la Statale 18 per protesta contro il trasferimento di alcuni ospiti ma anche per la situazione di disagio dovuta alla presenza di alcuni positivi nel centro<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>FUSCALDO (CS) &#8211; Protesta sulla statale 18 da parte di alcuni migranti ospiti del Cas di Fuscaldo, che si trova lungo la Statale al confine con il comune di Guardia Piemontese. In particolare a protestare \u00e8 stata una donna di origine nigeriana con un bambino di pochi mesi ed il marito. La donna <strong>si \u00e8 seduta al centro della carreggiata<\/strong> bloccando per alcuni minuti il traffico veicolare posizionando sull&#8217;asflato <strong>alcune valigie e materiali di plastica e <\/strong>denunciando la situazione di difficolt\u00e0 che si vive nel Cas dovuta all&#8217;isolamento, dopo che nei giorni scorsi sono stati <strong>riscontrati 5 casi di positivit\u00e0 al Covid<\/strong> e per chiedere che non vengano trasferiti alcuni ospiti in altri centri. Dopo pochi minuti la protesta \u00e8 rientrata anche per l&#8217;arrivo della polizia e il traffico \u00e8 tornato regolare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alcuni migranti ospiti del Cas di Fuscaldo hanno bloccato per alcuni minuti la Statale 18 per protesta contro il trasferimento di alcuni ospiti ma anche per la situazione di disagio dovuta alla presenza di alcuni positivi nel centro<\/p>\n","protected":false},"author":55,"featured_media":138313,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-138312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=138312"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/138313"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=138312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=138312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=138312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}