{"id":138499,"date":"2020-10-16T13:45:48","date_gmt":"2020-10-16T11:45:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/isolamento-battisti-difensori-valuteremo-se-chiedere-un-risarcimento\/"},"modified":"2023-01-16T18:08:35","modified_gmt":"2023-01-16T17:08:35","slug":"376519-isolamento-battisti-difensori-valuteremo-se-chiedere-un-risarcimento","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/376519-isolamento-battisti-difensori-valuteremo-se-chiedere-un-risarcimento\/","title":{"rendered":"Isolamento Battisti, difensori: &#8220;valuteremo se chiedere un risarcimento&#8221;"},"content":{"rendered":"<h4>Gli avvocati dell&#8217;ex terrorista: &#8221; <strong>chiediamo pubblicamente che ci sia l&#8217;intervento del Presidente del Consiglio o del Presidente della Repubblica<\/strong> affinch\u00e9 inducano i soggetti che hanno in carico Battisti al rispetto dei principi costituzionali e delle norme ordinarie&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CAGLIARI &#8211; Il magistrato di sorveglianza di Cagliari ha dichiarato il non luogo a procedere sul reclamo presentato dall&#8217;ex terrorista dei Pac, <strong>Cesare Battisti,<\/strong> per quello che ha sempre definito un<strong> &#8220;isolamento illegittimo&#8221;<\/strong> all&#8217;interno del carcere di Massama (Oristano). Secondo il giudice, come riferisce all&#8217;ANSA uno degli avvocati di Battisti, <strong>Gianfranco Sollai,<\/strong> con il trasferimento nell&#8217;istituto di Rossano lo scorso 14 settembre, non viene ravvisata <strong>&#8220;nessuna attualit\u00e0 di pregiudizio&#8221;<\/strong>. &#8220;Leggendo il dispositivo capiamo che evidentemente c&#8217;era un pregiudizio visto che i sei mesi di isolamento previsti come pena accessoria alla sua condanna sono terminati il 14 luglio 2019, mentre Battisti \u00e8 rimasto in tale situazione sino al 13 settembre 2020 &#8211; spiega Sollai &#8211; ora<strong> valuteremo se chiedere un eventuale risarcimento da proporre<\/strong> al giudice civile&#8221;.<\/p>\n<p>&#8220;La situazione del nostro assistito si \u00e8 aggravata &#8211; sottolinea Sollai che segue la difesa dell&#8217;ex Pac insieme al milanese <strong>Davide Steccanella e al calabrese Maurizio Nucci<\/strong> &#8211; mentre a Oristano la sua ottima condotta ha portato alla decisione sulla <strong>liberazione anticipata,<\/strong> a Rossano i rapporti disciplinari sono all&#8217;ordine del giorno e anche noi difensori abbiamo difficolt\u00e0 a comunicare con lui. Insomma &#8211; denuncia il legale &#8211; sino a questo momento lo Stato si \u00e8 rivelato vendicativo e noi <strong>chiediamo pubblicamente che ci sia l&#8217;intervento del Presidente del Consiglio o del Presidente della Repubblica<\/strong> affinch\u00e9 inducano i soggetti che hanno in carico Battisti al rispetto dei principi costituzionali e delle norme ordinarie&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli avvocati dell&#8217;ex terrorista: &#8221; chiediamo pubblicamente che ci sia l&#8217;intervento del Presidente del Consiglio o del Presidente della Repubblica affinch\u00e9 inducano i soggetti che hanno in carico Battisti al rispetto dei principi costituzionali e delle norme ordinarie&#8221;<\/p>\n","protected":false},"author":22,"featured_media":138500,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-138499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=138499"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/138500"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=138499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=138499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=138499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}