{"id":138559,"date":"2020-10-18T08:48:00","date_gmt":"2020-10-18T06:48:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/corigliano-stalking-e-lesioni-alla-ex-moglie-50enne-condannato-anche-in-appello\/"},"modified":"2023-01-16T18:08:39","modified_gmt":"2023-01-16T17:08:39","slug":"376734-corigliano-stalking-e-lesioni-alla-ex-moglie-50enne-condannato-anche-in-appello","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/376734-corigliano-stalking-e-lesioni-alla-ex-moglie-50enne-condannato-anche-in-appello\/","title":{"rendered":"Corigliano: stalking e lesioni alla ex moglie, 50enne condannato anche in appello"},"content":{"rendered":"<h4>I giudici di secondo grado, accogliendo le richieste dell\u2019accusa e della parte civile, hanno confermato la condanna per l\u2019ex marito della donna a sei mesi e 15 giorni di reclusione<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO-ROSSANO (CS)\u00a0 &#8211; La Corte di Appello di Catanzaro, in totale accoglimento delle richieste avanzate dal penalista Avv. Francesco Nicoletti, ha confermato la sentenza di condanna, per i reati di stalking e lesioni, emessa dal Tribunale di Castrovillari nei confronti di S.P.P., cinquantenne. L\u2019imputato \u00e8 stato, pertanto, riconosciuto responsabile di tali reati e condannato alla pena di mesi 6 e giorni 15 di reclusione, con l\u2019ulteriore condanna al pagamento di tutte le spese processuali sostenute della parte civile nonch\u00e9 al risarcimento di tutti i danni subiti dalla stessa.<\/p>\n<p>Nello specifico, l\u2019uomo si era reso responsabile di reiterate condotte di <strong>minaccia e molestia nei confronti dell\u2019ex moglie, con aggressioni fisiche<\/strong>, ingiurie, invio di sms dal contenuto minatorio, inseguimenti in auto e appostamenti, cagionandole un perdurante stato d\u2019ansia e di paura e ingenerandole il fondato timore per la propria incolumit\u00e0, cos\u00ec da costringerla a modificare ed alterare le proprie abitudini di vita e relazionali. In una occasione, mentre la donna si trovava all\u2019interno dell\u2019abitazione della sorella, l\u2019imputato, alla presenza anche delle figlie minorenni, la afferrava per i capelli e, reclinandole il capo impugnando una mannaia lunga circa 20 cm, la minacciava di morte procurandole lesioni poi refertate presso il Pronto Soccorso. In un\u2019altra occasione faceva irruzione armato di un bastone nella casa della sorella della persona offesa, dove questa si era rifugiata, e iniziava a rompere mobili e suppellettili. La vittima per sfuggire all\u2019ulteriore aggressione, in quanto minacciata di morte, era costretta a chiudersi in bagno con le figlie minori. L\u2019uomo desisteva dal suo intento criminale solo per il pronto intervento dei carabinieri che lo convincevano ad andare via. Tutti questi comportamenti avevano causato un grave stato di agitazione anche nelle figlie minori della coppia.<\/p>\n<p>A seguito della denuncia presentata dalla donna, l\u2019ex marito veniva sottoposto, con ordinanza di custodia cautelare emessa dal Gip del Tribunale di Castrovillari, al divieto di avvicinamento dei luoghi abitualmente frequentati dalla parte offesa. L\u2019ordinanza di custodia cautelare veniva poi confermata dal Tribunale di Catanzaro \u2013 Sezione Riesame \u2013 specificando che il non avvicinamento doveva riguardare, in particolare, il luogo di dimora della parte offesa, il luogo in cui questa prestava attivit\u00e0 lavorativa nonch\u00e9 il luogo di dimora delle due sorelle della vittima.<\/p>\n<p><strong>Condannato in primo grado, anche i giudici del secondo grado<\/strong> <strong>di giudizio hanno ritenuto l\u2019imputato responsabile dei reati di stalking e lesioni<\/strong> con condanna alla pena di mesi sei e giorni quindici di reclusione e con ulteriore condanna alle spese processuali anche del secondo grado di giudizio per come sostenute dalla parte civile costituita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I giudici di secondo grado, accogliendo le richieste dell\u2019accusa e della parte civile, hanno confermato la condanna per l\u2019ex marito della donna a sei mesi e 15 giorni di reclusione<\/p>\n","protected":false},"author":56,"featured_media":138560,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-138559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=138559"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/138560"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=138559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=138559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=138559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}