{"id":138815,"date":"2020-10-22T09:30:42","date_gmt":"2020-10-22T07:30:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/covid-19-meetup-rende-manna-chiuda-la-movida-a-quattromiglia\/"},"modified":"2023-01-16T18:08:57","modified_gmt":"2023-01-16T17:08:57","slug":"377404-covid-19-meetup-rende-manna-chiuda-la-movida-a-quattromiglia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/377404-covid-19-meetup-rende-manna-chiuda-la-movida-a-quattromiglia\/","title":{"rendered":"Covid 19, Meetup Rende: &#8220;Manna chiuda la movida a Quattromiglia&#8221;"},"content":{"rendered":"<h4>La richiesta riguarda in particolare la movida a Piazza Santo Sergio dove si creano numerose situazioni di assembramento pericolose<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE &#8211; \u201cIl Sindaco Manna si attivi immediatamente per chiudere la movida a Piazza Santo Sergio. I numeri del contagio stanno aumentando precipitosamente ed \u00e8 urgente agire dove si creano situazioni di assembramento e disporre la chiusura al pubblico nelle ore serali\u201d. \u00c8 la richiesta che gli attivisti del Meetup di Rende fanno al primo cittadino: \u201cdopo il nuovo DPCM e la circolare del Ministero dell\u2019Interno, <strong>i sindaci possono emanare ordinanze per la chiusura al pubblico<\/strong>, dopo le ore 21, delle strade o delle piazze nei centri urbani, dove, per via degli assembramenti, il contagio corre pi\u00f9 veloce, sigillando le zone interessate dalla cosiddetta \u2018movida\u2019, che difficilmente sono state controllabili nelle scorse settimane&#8221;.<\/p>\n<p>&#8220;<strong>Tanti sindaci in tutta Italia, proprio in queste ore, stanno operando in tal senso<\/strong> e Rende non pu\u00f2 pi\u00f9 permettere che gli studenti universitari, che nel caso dei fuorisede <strong>nel fine settimana<\/strong> tornano nei loro paesi di origine, in tutta la Calabria, soprattutto il <strong>mercoled\u00ec notte si assembrino a piazza Santo Sergio<\/strong>. Il sindaco Manna, quale autorit\u00e0 sanitaria nonch\u00e9 in qualit\u00e0 di ufficiale di governo, avrebbe gi\u00e0 dovuto intervenire a seguito delle numerose segnalazioni dei cittadini residenti nel quartiere Quattromiglia. Nelle ore serali e notturne, il mercoled\u00ec e fino a sabato, sono frequentissimi gli assembramenti di giovani, con un uso non adeguato delle mascherine e senza il rispetto delle distanze interpersonali&#8221;.<\/p>\n<p>&#8220;E c&#8217;\u00e8 anche un altro fenomeno molto preoccupante: a notte inoltrata, si sentono rombi di motore e si assiste a <strong>corse di moto a forte velocit\u00e0 tra via Leonardo da Vinci e via Alessandro Volta<\/strong>. Ma il Comune non \u00e8 mai intervenuto con un controllo serio sul territorio. Adesso, per\u00f2, &#8211; concludono gli attivisti pentastellati &#8211; visto i dati allarmanti di questi giorni, bisogna imporre delle regole per limitare i contagi Covid-19 e garantire la vigilanza necessaria per contenere la movida ed evitare assembramenti cos\u00ec deleteri per la nostra citt\u00e0 e per la Calabria tutta\u201d.<\/p>\n<p><strong>Immagine di repertorio\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La richiesta riguarda in particolare la movida a Piazza Santo Sergio dove si creano numerose situazioni di assembramento pericolose<\/p>\n","protected":false},"author":42,"featured_media":138816,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-138815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=138815"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/138815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/138816"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=138815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=138815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=138815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}