{"id":139110,"date":"2020-10-27T11:42:30","date_gmt":"2020-10-27T10:42:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/covid-mamma-positiva-da-alla-luce-una-bambina-sta-bene\/"},"modified":"2023-01-16T18:09:16","modified_gmt":"2023-01-16T17:09:16","slug":"378192-covid-mamma-positiva-da-alla-luce-una-bambina-sta-bene","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/378192-covid-mamma-positiva-da-alla-luce-una-bambina-sta-bene\/","title":{"rendered":"Covid: mamma positiva d\u00e0 alla luce una bambina, sta bene"},"content":{"rendered":"<h4>Si chiama Diletta e attualmente si trova nel reparto di neonatologia. La sua mamma \u00e8 positiva al Covid ma lei, dai primi controlli, \u00e8 negativa<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Un fiocco rosa di speranza in un periodo di continua emergenza, di pandemia. All&#8217;ospedale Pugliese di Catanzaro \u00e8 nata la piccola Diletta. La mamma \u00e8 positiva al coronavirus e la sua bimba \u00e8 negativa. Il parto cesareo \u00e8 avvenuto nel reparto di ostetricia e ginecologia, e poi la mamma \u00e8 tornata nel reparto Covid-19 per proseguire le cure.<\/p>\n<p>La notizia risale a due giorni fa ed il primario del reparto di Malattie infettive dell&#8217;ospedale di Catanzaro, Lucio Cosco: la bimba pesa 1,9 chili, sta bene e attualmente si trova nel reparto di Neonatologia. Cosco ha poi riferito che &#8220;<strong>anche la madre \u00e8 in buone condizioni<\/strong>, e se tutto procede bene la potremmo dimettere gi\u00e0 oggi&#8221;. Non \u00e8 il primo caso di di nascita da donna positiva all&#8217;ospedale a Catanzaro: un <strong>precedente si era gi\u00e0 registrato ad agosto<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si chiama Diletta e attualmente si trova nel reparto di neonatologia. La sua mamma \u00e8 positiva al Covid ma lei, dai primi controlli, \u00e8 negativa<\/p>\n","protected":false},"author":42,"featured_media":139111,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[681],"class_list":["post-139110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=139110"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/139111"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=139110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=139110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=139110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}