{"id":139122,"date":"2020-10-27T14:00:37","date_gmt":"2020-10-27T13:00:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-controlli-nei-luoghi-della-movida-manna-il-rispetto-delle-norme-anti-covid-e-massimo\/"},"modified":"2023-01-16T18:09:17","modified_gmt":"2023-01-16T17:09:17","slug":"378219-rende-controlli-nei-luoghi-della-movida-manna-il-rispetto-delle-norme-anti-covid-e-massimo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/378219-rende-controlli-nei-luoghi-della-movida-manna-il-rispetto-delle-norme-anti-covid-e-massimo\/","title":{"rendered":"Rende, controlli nei luoghi della movida. Manna: &#8220;il rispetto delle norme anti Covid \u00e8 massimo&#8221;"},"content":{"rendered":"<h4>Il sindaco: &#8220;stiamo monitorando piazze e luoghi di aggregazione. Sacrificare oggi i momenti di socialit\u00e0 vuol dire tornare il prima possibile ad una normalit\u00e0 che tutti agogniamo possa essere riconquistata il pi\u00f9 presto possibile&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; &#8220;Ieri sera ho potuto constatare quanto dichiarato nella mattinata rispetto al senso di responsabilit\u00e0 che, quotidianamente, palesa la nostra comunit\u00e0.&#8221; Cos\u00ec ha dichiarato il primo cittadino <strong>Marcello Manna<\/strong>. &#8220;Rende, &#8211; ha commentato &#8211; ancora una volta, dimostra unit\u00e0 e maturit\u00e0 rispetto a questo momento storico cos\u00ec critico. <strong>Il rispetto delle norme anti Covid \u00e8 massimo: sappiamo tutti che tutelare la nostra salute coincide col tutelare quella dei nostri cari e del prossimo.<\/strong> Ecco perch\u00e9 stiamo monitorando piazze e luoghi di aggregazione. Sacrificare oggi i momenti di socialit\u00e0 vuol dire tornare il prima possibile ad una normalit\u00e0 che tutti agogniamo possa essere riconquistata il pi\u00f9 presto possibile.<\/p>\n\n<p>Trovare le piazze che fino a poco tempo fa erano animate da tanti giovani vuote restituir\u00e0 tutta la misura di quanto sensibilizzare, lasciare al proprio autodeterminarsi nel rispetto degli altri sia terreno su cui \u00e8 stato possibile costruire, in questi mesi cos\u00ec ardui, un <strong>percorso sostenibile di ripartenza, di speranza concreta in un futuro pi\u00f9 solido.<\/strong> L\u2019auspicio \u00e8 che Rende non abbia bisogno di essere militarizzata: dimostriamo ancora una volta amor proprio e senso di appartenenza a una comunit\u00e0 coesa.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco: &#8220;stiamo monitorando piazze e luoghi di aggregazione. Sacrificare oggi i momenti di socialit\u00e0 vuol dire tornare il prima possibile ad una normalit\u00e0 che tutti agogniamo possa essere riconquistata il pi\u00f9 presto possibile&#8221;<\/p>\n","protected":false},"author":22,"featured_media":139123,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-139122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=139122"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/139123"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=139122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=139122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=139122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}