{"id":139318,"date":"2020-10-30T09:47:43","date_gmt":"2020-10-30T08:47:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/dipendente-aeroporto-denunciato-estraeva-criptovalute-con-i-pc-della-sacal\/"},"modified":"2023-01-16T18:09:30","modified_gmt":"2023-01-16T17:09:30","slug":"378752-dipendente-aeroporto-denunciato-estraeva-criptovalute-con-i-pc-della-sacal","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/378752-dipendente-aeroporto-denunciato-estraeva-criptovalute-con-i-pc-della-sacal\/","title":{"rendered":"Dipendente aeroporto denunciato: &#8216;estraeva&#8217; criptovalute con i pc della Sacal"},"content":{"rendered":"<h4>La Polizia postale ha denunciato un dipendente della Societ\u00e0 aeroportuale calabrese che utilizzava gli impianti della Sacal per &#8220;estrarre&#8221; criptovalute<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME &#8211; I guadagni offerti dalle nuove opportunit\u00e0 della tecnologica informatica erano diventati il suo chiodo fisso e cos\u00ec, avrebbe approfittato della sua posizione lavorativa all&#8217;interno dell&#8217;aeroporto di Lamezia Terme, per installare un malware e sfruttare l&#8217;infrastruttura informatica della Sacal spa, che gestisce gli aeroporti locali, per &#8220;estrarre&#8221; ovvero produrre moneta virtuale, mettendo in pericolo la sicurezza dell&#8217;infrastruttura critica.<\/p>\n<p>L&#8217;uomo, un addetto all&#8217;infrastruttura informatizzata dell&#8217;aeroporto di Lamezia Terme aveva avviato il <strong>business illegale nella convinzione di passare inosservato<\/strong> ma i tecnici della Sacal, sono stati allarmati da alcune anomalie sui sistemi informatici della rete tecnologica aeroportuale, ed hanno attivato la Polizia di frontiera, che ha richiesto l\u00b4intervento degli esperti della Polizia postale.<\/p>\n<p>Analizzando le partizioni della rete informatica interna all&#8217;hub aeroportuale, gli investigatori hanno scoperto la presenza, in due differenti locali tecnici, di una vera e propria &#8220;<strong>Mining Farm<\/strong>&#8220;, una <strong>rete abusiva composta da ben cinque potenti elaboratori elettronici,<\/strong> denominati &#8220;Mining Rig&#8221;, termine con il quale si indicano in gergo tecnico i sistemi utilizzati per la creazione di bitcoin o altre criptovalute, collegati alla rete Internet esterna attraverso i sistemi dedicati alla gestione dei servizi aeroportuali ed alimentati attraverso la fornitura di energia elettrica dell&#8217;aeroporto.<\/p>\n<p><iframe loading=\"lazy\" title=\"Denunciato dipendente Sacal\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/n2WZJ31fzQ4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>La sofisticata architettura ha consentito all&#8217;utilizzatore del sistema integrato con la rete aeroportuale di approvvigionarsi della <strong>criptovaluta &#8220;Ethereum<\/strong>&#8220;, prodotta senza sostenere le ingenti spese di energia elettrica necessaria per il funzionamento h24 delle apparecchiature e sfruttando la connettivit\u00e0 fornita dagli impianti infotelematici della Sacal, compromettendo la sicurezza ed esponendo i sistemi di gestione dello scalo.<\/p>\n<p>Le indagini, coordinate dalla Procura di Lamezia Terme, sono state condotte con attivit\u00e0 tecniche che hanno consentito di esaminare gli indirizzi IP abbinati alle macchine installate, di individuare il sito del Pool &#8220;Ethermine&#8221; (utilizzato per minare criptovaluta Ethereum) e di monitorare il sito, e con appostamenti e servizi di osservazione con telecamere installate nei luoghi interessati, che hanno consentito l&#8217;individuazione <strong>del 41enne<\/strong>. Le indagini proseguono per accertare la presenza di eventuali complici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polizia postale ha denunciato un dipendente della Societ\u00e0 aeroportuale calabrese che utilizzava gli impianti della Sacal per &#8220;estrarre&#8221; criptovalute<\/p>\n","protected":false},"author":42,"featured_media":139319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-139318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=139318"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/139319"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=139318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=139318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=139318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}