{"id":139394,"date":"2020-10-31T13:13:29","date_gmt":"2020-10-31T12:13:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/casa-per-anziani-di-casali-del-manco-al-via-i-trasferimenti\/"},"modified":"2023-01-16T18:09:35","modified_gmt":"2023-01-16T17:09:35","slug":"378921-casa-per-anziani-di-casali-del-manco-al-via-i-trasferimenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/378921-casa-per-anziani-di-casali-del-manco-al-via-i-trasferimenti\/","title":{"rendered":"Casa per anziani di Casali del Manco, al via i trasferimenti"},"content":{"rendered":"<h4>Gli anziani, positivi al Covid-19, vengono trasferiti nell&#8217;ospedale di Rossano dove riceveranno tutta l&#8217;assistenza necessaria<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CASALI DEL MANCO (CS) &#8211; La task force dell&#8217;Asp di Cosenza, dopo aver richiesto e ottenuto il via dalla Regione Calabria, sta provvedendo a trasferire gli anziani ospiti in una casa protetta nella frazione di Spezzano Piccolo di Casali del Manco. Gli anziani, positivi al Covid-19, grazie agli operatori e mezzi del 118 raggiungeranno il nuovo reparto Covid dell&#8217;ospedale di Rossano, che apre i battenti proprio oggi. Inoltre, per rendere disponibili alcuni posti letto, cinque pazienti in via di miglioramento, finora ospitati in Terapia intensiva e nel reparto di Malattie infettive dell&#8217;ospedale dell&#8217;Annunziata di Cosenza, sono stati destinati a cure domiciliari.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Gli anziani, positivi al Covid-19, vengono trasferiti nell&#8217;ospedale di Rossano dove riceveranno tutta l&#8217;assistenza necessaria<\/p>\n","protected":false},"author":56,"featured_media":139395,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-139394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=139394"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139394\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/139395"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=139394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=139394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=139394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}