{"id":139443,"date":"2020-11-02T11:47:40","date_gmt":"2020-11-02T10:47:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/saracena-installata-nel-cimitero-lopera-di-sancineto-luomo-in-cristo\/"},"modified":"2023-01-16T18:09:38","modified_gmt":"2023-01-16T17:09:38","slug":"379045-saracena-installata-nel-cimitero-lopera-di-sancineto-luomo-in-cristo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/379045-saracena-installata-nel-cimitero-lopera-di-sancineto-luomo-in-cristo\/","title":{"rendered":"Saracena, installata nel cimitero l&#8217;opera di Sancineto &#8220;L&#8217;uomo in Cristo&#8221;"},"content":{"rendered":"<h4>L&#8217;opera dell&#8217;artista castrovillarese Mimmo Sancineto era stata donata all\u2019amministrazione del comune del Pollino 23 anni fa ma giaceva inutilizzata<br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SARACENA (CS) &#8211; Una cerimonia semplice ma carica di significato quella svolta ieri presso il cimitero di Saracena per inaugurare l&#8217;installazione dell&#8217;opera &#8220;<strong>L&#8217;uomo in cristo<\/strong>&#8221; dell&#8217;artista castrovillari Mimmo Sancineto. Il <strong>crocifisso di tre metri e mezzo<\/strong> per una <strong>larghezza di due metri<\/strong> era stata donata ben <strong>32 anni fa al comune di Saracena ma giaceva inutilizzata<\/strong>. L&#8217;amministrazione guidata dal sindaco, Renzo Russo, ha inteso invece dare valore e riconoscimento all&#8217;opera ed all&#8217;artista che di sua spontanea volont\u00e0 nel 1988 aveva donato l&#8217;opera in ferro da lui realizzata al comune del Pollino.<\/p>\n<p>Con una semplice cerimonia, anche per le ristrettezze del momento emergenziale, il sindaco, il suo vice Biagio Diana, ed altri membri della giunta insieme ai parrocci della comunit\u00e0 don Leone Boniface e don Rocco Lategano si sono ritrovati negli spazi del cimitero cittadino per inaugurare e benedire l&#8217;opera che da oggi ricorder\u00e0 ai passanti, proprio come nella volont\u00e0 dell&#8217;artista, le <strong>sofferenze del cristo che si fa uomo<\/strong> ed assume su di s\u00e8 il dolore del mondo. Un ringraziamento particolare \u00e8 stato rivolto all&#8217;artista dall&#8217;amministrazione comunale di Saracena per la sensibilit\u00e0 e l&#8217;attenzione dimostrata nei confronti della comunit\u00e0 gi\u00e0 arricchita, nel passato, da opere che impreziosiscono la pinacoteca comunale fiore all&#8217;occhiello museale della realt\u00e0 saracenara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;opera dell&#8217;artista castrovillarese Mimmo Sancineto era stata donata all\u2019amministrazione del comune del Pollino 23 anni fa ma giaceva inutilizzata<\/p>\n","protected":false},"author":42,"featured_media":139444,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-139443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=139443"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/139444"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=139443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=139443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=139443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}