{"id":139799,"date":"2020-11-08T09:06:54","date_gmt":"2020-11-08T08:06:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sequestrato-a-morano-calabro-il-centro-raccolta-rifiuti-comunale\/"},"modified":"2023-01-16T18:10:03","modified_gmt":"2023-01-16T17:10:03","slug":"380002-sequestrato-a-morano-calabro-il-centro-raccolta-rifiuti-comunale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/380002-sequestrato-a-morano-calabro-il-centro-raccolta-rifiuti-comunale\/","title":{"rendered":"Sequestrato a Morano Calabro il Centro Raccolta Rifiuti Comunale"},"content":{"rendered":"<h4>Il provvedimento \u00e8 stato emesso dal GIP del Tribunale di Castrovillari ed eseguito dai carabinieri Forestali di Castrovillari e Oriolo<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MORANO CALABRO (CS) &#8211; E&#8217; finito sotto sequestro il Centro Raccolta Rifiuti Comunale di c.da Fineta di Morano Calabro. Il provvedimento \u00e8 stato assunto a seguito dell\u2019attivit\u00e0 dei militari forestali che hanno evidenziato alcune <strong>irregolarit\u00e0 in violazione alle norme<\/strong> che regolano la gestione dei siti atti alla raccolta come il conferimento al suo interno di <strong>rifiuti indifferenziati<\/strong>.<\/p>\n<p>L\u2019autorizzazione a tale attivit\u00e0 prevede infatti il conferimento solo di rifiuti differenziati tra loro. L\u2019attivit\u00e0 riscontrata <strong>nell\u2019Isola ecologica non rispecchia in termini gestionali<\/strong> quanto imposto dalla normativa configurando di fatto l\u2019ipotesi di reato di gestione illecita di rifiuti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il provvedimento \u00e8 stato emesso dal GIP del Tribunale di Castrovillari ed eseguito dai carabinieri Forestali di Castrovillari e Oriolo<\/p>\n","protected":false},"author":42,"featured_media":139800,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-139799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=139799"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/139800"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=139799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=139799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=139799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}