{"id":139925,"date":"2020-11-10T12:09:59","date_gmt":"2020-11-10T11:09:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/san-giovanni-in-fiore-guccione-a-rischio-il-servizio-oncologia\/"},"modified":"2023-01-16T18:10:11","modified_gmt":"2023-01-16T17:10:11","slug":"380345-san-giovanni-in-fiore-guccione-a-rischio-il-servizio-oncologia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/380345-san-giovanni-in-fiore-guccione-a-rischio-il-servizio-oncologia\/","title":{"rendered":"San Giovanni in Fiore, Guccione: &#8220;a rischio il servizio oncologia&#8221;"},"content":{"rendered":"<h4>Il consigliere regionale del pd Carlo Guccione, parla di &#8220;decisione senza logica da parte dell&#8217;Asp di Cosenza che rischia di bloccare il servizio&#8221;<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>SAN GIOVABNNI IN FIORE (CS) &#8211; Ancora una volta l&#8217;Asp di Cosenza continua ad adottare disposizioni senza tenere minimamente conto delle esigenze dei cittadini e dei territori. Decisioni che rischiano di bloccare il servizio di oncologia all&#8217;ospedale di San Giovanni in Fiore. \u00c8 quanto dichiara Carlo Guccione consigliere regionale del Pd.<\/p>\n<p>&#8220;L&#8217;Unit\u00e0 semplice di Oncologia medica di San Giovanni in Fiore, diretta dal dottor Antonio Caputo, &#8211; continua Guccione &#8211; \u00e8 stata istituita nel 2009 e aggregata all&#8217;U.O.C. di oncologia di Paola. Per carenza di medici, i dirigenti dell&#8217;Asp di Cosenza hanno cos\u00ec deciso di inserire il dottor Caputo nei turni di Medicina. Una decisione senza logica visto che, San Giovanni in Fiore, in virt\u00f9 delle disposizioni di servizio del responsabile di Oncologia, cessa di essere aggregato all&#8217;U.O.C. di Paola venendo meno la possibilit\u00e0 di essere inseriti nei registri Aifa e di prescrivere farmaci oncologici. Prima di prendere determinati provvedimenti sarebbe il caso di informarsi bene ed evitare un eventuale blocco di un servizio fondamentale ad assicurare le migliori cure terapeutiche ai cittadini e i cicli di chemio ai pazienti affetti da tumore. La commissaria dell&#8217;Asp di Cosenza, Simonetta Cinzia Bettelini, metta in atto tutte le misure necessarie a impedire che dal 15 novembre venga chiusa l&#8217;Unit\u00e0 oncologica di San Giovanni in Fiore. Una scelta che, soprattutto in questo momento di diffusione della pandemia, non terrebbe conto dei pazienti pi\u00f9 fragili che hanno bisogno di cure immediate e non possono fare lunghi viaggi per avere diritto alla chemioterapia, rischiando di contrarre il virus&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il consigliere regionale del pd Carlo Guccione, parla di &#8220;decisione senza logica da parte dell&#8217;Asp di Cosenza che rischia di bloccare il servizio&#8221;<\/p>\n","protected":false},"author":56,"featured_media":139926,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-139925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=139925"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/139926"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=139925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=139925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=139925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}