{"id":139993,"date":"2020-11-11T12:13:51","date_gmt":"2020-11-11T11:13:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/morano-calabro-chiuse-le-scuole-da-domani-e-fino-al-3-dicembre\/"},"modified":"2023-01-16T18:10:17","modified_gmt":"2023-01-16T17:10:17","slug":"380520-morano-calabro-chiuse-le-scuole-da-domani-e-fino-al-3-dicembre","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/380520-morano-calabro-chiuse-le-scuole-da-domani-e-fino-al-3-dicembre\/","title":{"rendered":"Morano Calabro, chiuse le scuole da domani e fino al 3 dicembre"},"content":{"rendered":"<h4>Il sindaco Nicol\u00f2 De Bartolo, in via cautelativa, ha disposto da gioved\u00ec 12 novembre a gioved\u00ec 3 dicembre 2020 la sospensione di tutte le attivit\u00e0 didattiche presso le scuole di ogni ordine e grado. Consentita la didattica a distanza<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MORANO CALABRO (CS) &#8211; La decisione \u00e8 stata presa questa mattina dal sindaco Nicol\u00f2 De Bartolo, per &#8220;tutelare con ogni possibile iniziativa la salute dei ragazzi e scaturisce da un\u2019attenta analisi della situazione sanitaria generale e, segnatamente, dalla presenza di alcuni casi positivi al Covid-19 in ambito locale, contingenza che richiede particolare attenzione e prudenza&#8221;.<\/p>\n<p>&#8220;Agli alunni portatori di disabilit\u00e0 e\/o con problemi di apprendimento &#8211; ha poi precisato il primo cittadino &#8211; \u00e8 permessa la frequentazione dell\u2019Istituto previo accordo tra la Dirigenza scolastica e il nucleo familiare interessato. Lo svolgimento delle attivit\u00e0 amministrative interne dipenderanno, invece, dai provvedimenti del Dirigente Scolastico, le cui autonome iniziative circa l\u2019organizzazione della DAD e dello Smart-Working rimangono impregiudicate. Valgono, oggi pi\u00f9 che mai, le raccomandazioni ad attenersi scrupolosamente alle regole di contenimento della malattia. Nello specifico si ricorda di rimanere a casa e di uscire solo per i motivi consentiti dalle norme vigenti in materia di gestione dell\u2019epidemia. Usiamo sempre i dispositivi di protezione (mascherine) e limitiamo i contatti, mantenendo, comunque, la distanza di almeno un metro dalle persone. Il testo integrale dell\u2019ordinanza \u00e8 disponibile nel sito istituzionale dell\u2019Ente, nelle sezioni: \u201cAlbo pretorio\u201d e \u201cNotizie dall\u2019Ente\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco Nicol\u00f2 De Bartolo, in via cautelativa, ha disposto da gioved\u00ec 12 novembre a gioved\u00ec 3 dicembre 2020 la sospensione di tutte le attivit\u00e0 didattiche presso le scuole di ogni ordine e grado. Consentita la didattica a distanza<\/p>\n","protected":false},"author":56,"featured_media":139994,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-139993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=139993"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/139993\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/139994"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=139993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=139993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=139993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}