{"id":140334,"date":"2020-11-22T08:00:33","date_gmt":"2020-11-22T07:00:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/adolescenti-tra-didattica-a-distanza-e-rischio-sedentarieta-consigli-ed-esercizi\/"},"modified":"2023-01-16T18:10:40","modified_gmt":"2023-01-16T17:10:40","slug":"381393-adolescenti-tra-didattica-a-distanza-e-rischio-sedentarieta-consigli-ed-esercizi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/381393-adolescenti-tra-didattica-a-distanza-e-rischio-sedentarieta-consigli-ed-esercizi\/","title":{"rendered":"Adolescenti tra didattica a distanza e rischio sedentariet\u00e0. La Azzolina &#8220;riapriamo le scuole&#8221;"},"content":{"rendered":"<h4>Il 2020 \u00e8 un anno che gli adolescenti difficilmente dimenticheranno: scuola, attivit\u00e0 ricreative e sport sono stati penalizzati dalle misure di contenimento del Covid 19. <strong>E le ore eccessive al PC possono indurre un adolescente all\u2019apatia e a non provare interesse per il mondo esterno. <\/strong>Intanto la ministra dell&#8217;istruzione spiega &#8220;collaboriamo tutti per riaprire le scuole ai ragazzi. Lo si faccia al pi\u00f9 presto&#8221; <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; La pandemia in corso rischia di <strong>rendersi responsabile di molti effetti collaterali ai danni dei ragazzi<\/strong> che subiscono le restrizioni, certo a favore del contrasto del virus, ma sicuramente a svantaggio della psiche e <strong>dell\u2019apparato muscolo scheletrico<\/strong>. Il ricorso alla didattica distanza, ad esempio, deve poter consentire ai ragazzi che trascorrono molte ore seduti alla scrivania davanti al computer, di mantenere comunque in salute la colonna vertebrale nella delicatissima fase della crescita dell\u2019apparato scheletrico, a cui si aggiunge il rischio obesit\u00e0 a causa della sedentariet\u00e0 a cui sono costretti, come <strong>documentato dal Primo Rapporto Italiano Barometro Obesit\u00e0 realizzato da IBDO Foundation e Istat<\/strong>, che ha fotografato un preoccupante incremento della situazione con ripercussioni sulla qualit\u00e0 della vita delle persone che ne sono affette. Secondo il Rapporto, In Italia, il 46% degli adulti, ovvero oltre 23 milioni di persone, e il 24,2% tra bambini e adolescenti, che corrisponde ad 1 milione e 700mila persone, \u00e8 sovrappeso.<\/p>\n<p>Nell&#8217;ultima settimana appena trascorsa <strong>151 mila alunni calabresi dalla scuola dell&#8217;infanzia alla prima media e 68 mila alunni toscani di seconda e terza media hanno seguito le lezioni da casa<\/strong>, come i compagni pi\u00f9 grandi. Tra restrizioni con ordinanze regionali e zone rosse dovute al Dpcm,<strong> sono 3.894.278 gli alunni complessivamente impegnati nella didattica a distanza, il 46,2%del totale<\/strong>.\u00a0La ministra dell&#8217;istruzione Azzolina spinge per riaprire al pi\u00f9 presto le classi ai ragazzi e chiede la collaborazione di tutti &#8220;<strong>\u00e8 falso che &#8216;al Ministero dell&#8217;Istruzione si d\u00e0 ormai per scontato che anche a dicembre tutti gli studenti resteranno a casa<\/strong>&#8216; ha scritto la ministra &#8220;l&#8217;unica cosa per me scontata \u00e8 che siano tutti d&#8217;accordo, e che <strong>tutti collaborino, per riportare quanto prima in classe studentesse e studenti<\/strong> che al momento stanno facendo didattica digitale a distanza. Io sto lavorando per questo&#8221;. Lucia Azzolina ha smentito alcune frasi che le sono state attribuite. In particolare, scrive Azzolina, &#8220;stamani su &#8216;La Repubblica&#8217; mi vengono attribuite parole mai pronunciate, in riferimento alla riapertura delle scuole: &#8220;<strong>La data del 4 dicembre \u00e8 troppo vicina per programmare ogni cosa<\/strong>&#8220;. Mai detto.<strong> Falso anche un passaggio secondo il quale mi sarei opposta<\/strong> &#8220;per tutta l&#8217;estate ad un piano condiviso sui trasporti&#8221;.\u00a0La Azzolina, pur desiderando fortemente che i ragazzi tornino in classe, non azzarda date sulla riapertura delle scuole per gli studenti che in queste settimane sono costretti a studiare &#8216;a distanza&#8217;. La titolare del Miur non nasconde qualche stoccata ai governatori, veloci a chiudere le scuole, e fa notare che<strong> &#8220;purtroppo questo \u00e8 un Paese in cui il ministro non pu\u00f2 decidere su chiusure e aperture mentre altre autorit\u00e0 possono farlo<\/strong>&#8220;.<br \/>\n<a href=\"https:\/\/quicosenza.it\/news\/11742\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-381398\" src=\"https:\/\/quicosenza.it\/news\/11742\" alt=\"\" width=\"542\" height=\"326\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Intanto a ricordarne i rischi e lanciare l\u2019allarme \u00e8 <strong>l\u2019Associazione Italia Chiropratici<\/strong> (Aic), che evidenzia come diabete, cancro e malattie cardiocircolatorie siano tra le principali cause di morte nel mondo.<strong> Il sovrappeso e l&#8217;obesit\u00e0 possono aumentare la degenerazione del disco vertebrale<\/strong>. A causa dell&#8217;aumento del carico sulla colonna vertebrale, i dischi intervertebrali sono sotto costante compressione, limitando la mobilit\u00e0 spinale. Nonostante la gravit\u00e0 e il peso corporeo aumentano la struttura vertebrale rimane la medesima . Quindi avremo maggior probabilit\u00e0 di provocare in primis protrusioni e poi ernie che interessano i dischi sia della colonna lombare che cervicale e alterazioni delle curve fisiologiche della colonna stessa.<\/p>\n<h4>Quali sono i rischi della sedentariet\u00e0 per gli adolescenti? Quali sono le posizioni sbagliate da evitare? Al computer, seduti al banco a scuola, durante la didattica a distanza a casa?<\/h4>\n<p>\u00ab Mentre si legge &#8211; spiega Consuelo Podio, Dottoressa in Chiropratica U.S.A. &#8211; \u00e8 necessario tenere una postura adeguata. \u00c8 sconsigliato leggere da sdraiati sia sul letto che sul divano. Bisognerebbe stare seduti ed attivare cos\u00ec gli estensori della colonna vertebrale. Da seduti, su una sedia con schienale continuo , \u00e8 utile poggiare bene i piedi sul pavimento, se si vogliono riposare le gambe leggermente rialzate su un poggiapiedi traverso. Le spalle devono essere rilassate e, se possibile, \u00e8 meglio preferire una sedia con dei braccioli per far riposare le braccia. La testa dritta con il mento indentro e occhi in linea con il testo che si legge, sia che si tratti di un libro che del monitor del pc. Se si \u00e8 costretti a studiare tramite la didattica a distanza i genitori dovrebbero ridurre i tempi di utilizzo del cellulare e del pc in situazioni ludiche; \u00e8 stata verificata una correlazione tra stimolo del cervello attraverso il monitor e aumento di aggressivit\u00e0 del bambino- adolescente. Se si studia durante le lezioni da remoto con lo smartphone assolutamente tenere lo schermo ad altezza occhi senza inclinarli verso il basso. Ogni due ore \u00e8 consigliato alzarsi per cambiare posizione e sgranchirsi le gambe\u00bb.<\/p>\n<h4>Quali sono gli esercizi da poter fare a casa?<\/h4>\n<p><strong>Gatto<\/strong> (posizione a carponi): il movimento parte dal coccige ad onda dal basso verso l\u2019alto . Il coccige si muove con la cervicale , la parte toracica invece svolge un movimento opposto.<\/p>\n<p><strong>Ginocchia al petto<\/strong>: posizione supina, si piegano le ginocchia al petto stirando la colonna e continuando a respirare nell\u2019addome.<\/p>\n<p><strong>Semiponte<\/strong>: posizione supina, ginocchia piegate e glutei contratti. Da questa posizione portare in alto la schiena e rimanere per 20 secondi in tensione. \u00c8 un esercizio di resistenza.<\/p>\n<p><strong>Superman<\/strong>: posizione prona: sollevare un braccio per volta e portarlo in posizione tesa, rimanere in sospensione per 25 secondi. Ripetere il movimento per altro braccio e gambe.<\/p>\n<p><strong>Movimento caviglie e mani<\/strong>: in posizione supina comporre un movimento rotatorio dei polsi e delle caviglie (sia senso orario che antiorario).<\/p>\n<p><strong>Stretching delle braccia<\/strong>: in piedi incrociare le dita e portare le braccia verso l\u2019alto e indietro circa 6 volte. Successivamente riportare le braccia verso il basso e girare le mani verso l\u2019esterno incrociate, ripetere l\u2019 estensione altre 6 volte verso l\u2019alto.<\/p>\n<h4>Quando \u00e8 il caso di contattare un Dottore Chiropratico?<\/h4>\n<p>Nel caso si avvertano mal di testa, vertigini o problemi cervicali, lombalgia, dolori intercostali.<\/p>\n<h4>Come pu\u00f2 aiutare la Chiropratica in questi casi? Pu\u00f2 intervenire anche a livello psicologico?<\/h4>\n<p>La Chiropratica migliora la coordinazione dei movimenti nello sport, elimina le sublussazioni vertebrali riducendo l\u2019infiammazione tissutale. Inoltre ristabilisce la buona biomeccanica articolare, migliora la qualit\u00e0 del sonno e la concentrazione. Dal punto di vista psicologico sappiamo che durante un aggiustamento chiropratico vengono prodotte endorfine che stimolano il buon umore e diminuiscono il dolore fisico.<\/p>\n<p><strong>Le ore eccessive al PC possono indurre un adolescente all\u2019apatia e a non provare interesse per il mondo esterno<\/strong>, anche in questo l\u2019approccio alla Chiropratica aiuta molto i ragazzi. Il Dottore in Chiropratica \u00e8 in grado di trovare e correggere le sublussazioni vertebrali e stimolare maggior flessibilit\u00e0 nella colonna. La propriocezione , la capacit\u00e0 di sentire il corpo nello spazio, aumenta ed il paziente \u00e8 in grado di controllare meglio l\u2019appoggio plantare e la postura in movimento. <strong>I soggetti che soffrono di obesit\u00e0<\/strong> avranno anche la tendenza a degenerare patologie pregresse sui menischi delle ginocchia che, essendo cartilaginei come i dischi della colonna, servono a diminuire lo shock e l\u2019attrito. Anche in questi casi un intervento chiropratico, attraverso l\u2019aggiustamento di anca, ginocchio e caviglia indirizzando la catena cinematica, gestisce meglio il peso che si scarica sulla parte inferiore del corpo e ritarda la degenerazione. Inoltre l\u2019aggiustamento chiropratico produce endorfine e diminuisce lo stimolo sul tratto neurologico ipotalamo \u2013 pituitaria \u2013 surrenale diminuendo il cortisolo, ha quindi un\u2019azione equilibrante a livello ormonale. Studi condotti in Australia, presso la Curtin University, hanno dimostrato che bambini e adolescenti obesi hanno maggior rischio di sviluppare una cattiva postura. Questo elemento \u00e8 considerato critico perch\u00e9 con una cattiva postura il rischio di diventare adulti con mal di schiena cronico \u00e8 molto elevato.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 2020 \u00e8 un anno che gli adolescenti difficilmente dimenticheranno: scuola, attivit\u00e0 ricreative e sport sono stati penalizzati dalle misure di contenimento del Covid 19. E le ore eccessive al PC possono indurre un adolescente all\u2019apatia e a non provare interesse per il mondo esterno. Intanto la ministra dell&#8217;istruzione spiega &#8220;collaboriamo tutti per riaprire le [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":140335,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,52],"tags":[],"class_list":["post-140334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/140334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=140334"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/140334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/140335"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=140334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=140334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=140334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}