{"id":140377,"date":"2020-11-17T16:02:13","date_gmt":"2020-11-17T15:02:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/covid-positivi-due-cancellieri-al-tribunale-di-castrovillari\/"},"modified":"2023-01-16T18:10:43","modified_gmt":"2023-01-16T17:10:43","slug":"381492-covid-positivi-due-cancellieri-al-tribunale-di-castrovillari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/381492-covid-positivi-due-cancellieri-al-tribunale-di-castrovillari\/","title":{"rendered":"Covid, positivi due cancellieri al tribunale di Castrovillari"},"content":{"rendered":"<h4>I dipendenti hanno scoperto di aver contratto il virus a seguito di uno screening effettuato sul personale. Domani il palazzo di giustizia rester\u00e0 chiuso per la sanificazione<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CASTROVILLARI (CS) &#8211; Il contagio da Covid-19 colpisce i<strong>l tribunale di Castrovillari<\/strong>. Si tratta due i cancellieri che hanno scoperto la positivit\u00e0 al virus a seguito dello screening effettuato sul personale del Tribunale. Immediatamente \u00e8 scattato il protocollo che prevede la sanificazione e la messa in quarantena dei colleghi dello stesso ufficio dei cancellieri. Lo <strong>screening effettuato sul personale di cancelleria<\/strong>, magistrati e operanti nel tribunale, a quanto abbiamo appreso, avrebbe in totale permesso di verificare la posizione di almeno 2<strong>50 operatori della giustizia<\/strong>. Allo stato mancano i risultati di una settantina di tamponi. Domani il palazzo di giustizia rester\u00e0 chiuso per la sanificazione.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I dipendenti hanno scoperto di aver contratto il virus a seguito di uno screening effettuato sul personale. Domani il palazzo di giustizia rester\u00e0 chiuso per la sanificazione<\/p>\n","protected":false},"author":58,"featured_media":140378,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-140377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/140377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=140377"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/140377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/140378"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=140377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=140377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=140377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}