{"id":140420,"date":"2020-11-21T12:00:27","date_gmt":"2020-11-21T11:00:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/premioscuoladigitale-videogioco-su-cambiamenti-clima-i-vincitori\/"},"modified":"2023-01-16T18:10:46","modified_gmt":"2023-01-16T17:10:46","slug":"381624-premioscuoladigitale-videogioco-su-cambiamenti-clima-i-vincitori","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/381624-premioscuoladigitale-videogioco-su-cambiamenti-clima-i-vincitori\/","title":{"rendered":"#PremioScuolaDigitale: videogioco su cambiamenti clima, i vincitori"},"content":{"rendered":"<h4>Due i progetti vincitori del l&#8217;iniziativa del Ministero dell&#8217;Istruzione nata per promuovere le <strong>eccellenze delle scuole italiane nell&#8217;apprendimento e nell&#8217;insegnamento digitali<\/strong><br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Un videogioco, dal titolo &#8220;Il mago del clima&#8221;, per sensibilizzare i pi\u00f9 piccoli sui problemi che derivano dal riscaldamento globale e una sedia a rotelle trasformata, grazie alla tecnologia, in uno strumento per esercizi riabilitativi programmabili. Sono i due progetti vincitori del l&#8217;iniziativa del Ministero dell&#8217;Istruzione nata per promuovere le <strong>eccellenze delle scuole italiane nell&#8217;apprendimento e nell&#8217;insegnamento digitali<\/strong>.<\/p>\n<p>Il premio, quest&#8217;anno, \u00e8 stato esteso a tutte le <strong>istituzioni scolastiche del primo e secondo ciclo di istruzione<\/strong>. Le scuole hanno candidato progetti tesi a valorizzare modelli didattici innovativi e sperimentali, percorsi di apprendimento curricolari ed extracurricolari basati sulle tecnologie digitali, prototipi tecnologici e applicazioni.<\/p>\n<p>Il #<strong>PremioScuolaDigitale<\/strong> si \u00e8 svolto attraverso una fase provinciale e una successiva fase regionale. Hanno partecipato <strong>784 scuole<\/strong> del primo ciclo e <strong>536 scuole del secondo ciclo<\/strong>, coinvolgendo <strong>35.000 tra studentesse e studenti e oltre 2.500 docenti referenti per i singoli progetti<\/strong>.<\/p>\n<p>L&#8217;Istituto comprensivo &#8220;<strong>Oton Zupancic&#8221; di Gorizia<\/strong> si \u00e8 aggiudicato il primo premio nella sezione dedicata al primo ciclo, grazie al &#8220;Mago del clima&#8221;, un videogioco dedicato al tema del cambiamento climatico i cui disegni sono stati realizzati interamente dai bambini, cos\u00ec come tutte le istruzioni. Dei piccoli alunni sono anche le voci narranti. Gli studenti si sono esercitati, nel loro percorso didattico, con il coding e, in particolare, con il programma Scratch, imparando a programmare varie tipologie di videogioco.<\/p>\n<p>L&#8217;Istituto <strong>&#8220;Olivetti&#8221; di Ivrea<\/strong> ha vinto, invece, il primo premio nella sezione del secondo ciclo grazie al progetto &#8216;Perla&#8217; (Programmable Exercises for Rehabilitation of Legs and Arms) attraverso il quale gli studenti hanno creato un ausilio capace di mobilizzare le articolazioni di quelle persone che, per problemi dovuti a incidenti, patologie degenerative o, semplicemente, a causa dell&#8217;et\u00e0, hanno difficolt\u00e0 nei movimenti di braccia e gambe. Grazie a due braccioli automatizzati, che vengono applicati su una sedia a rotelle e sono realizzati con materiali riciclati e di basso costo, gli utilizzatori potranno riacquistare capacit\u00e0 motorie di base. Il progetto \u00e8 stato sviluppato in collaborazione con un fisioterapista (ex studente della scuola) e una persona con disabilit\u00e0.<\/p>\n<p>&#8220;Alle scuole vincitrici, ma anche a tutte quelle che hanno partecipato, faccio i miei complimenti per l&#8217;impegno e la capacit\u00e0 avuta di mettersi in gioco, per aver colto, nella difficile sfida del momento, un&#8217;opportunit\u00e0 straordinaria di cambiamento e di partecipazione &#8211; ha commentato la <strong>ministra dell&#8217;Istruzione Lucia Azzolina<\/strong> -. Come Ministero crediamo nel cambiamento e nell&#8217;innovazione. L&#8217;ampia partecipazione a questo premio nazionale ci dimostra che siamo in tanti a crederci&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Due i progetti vincitori del l&#8217;iniziativa del Ministero dell&#8217;Istruzione nata per promuovere le eccellenze delle scuole italiane nell&#8217;apprendimento e nell&#8217;insegnamento digitali<\/p>\n","protected":false},"author":42,"featured_media":140421,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-140420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/140420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=140420"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/140420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/140421"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=140420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=140420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=140420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}