{"id":140484,"date":"2020-11-21T13:00:39","date_gmt":"2020-11-21T12:00:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-manna-servizio-prenotazioni-online-efficiente-per-rilascio-carte-didentita\/"},"modified":"2023-01-16T18:10:49","modified_gmt":"2023-01-16T17:10:49","slug":"381776-rende-manna-servizio-prenotazioni-online-efficiente-per-rilascio-carte-didentita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/381776-rende-manna-servizio-prenotazioni-online-efficiente-per-rilascio-carte-didentita\/","title":{"rendered":"Rende, Manna: &#8220;servizio prenotazioni online efficiente per rilascio carte d\u2019identit\u00e0&#8221;"},"content":{"rendered":"<h4>La modalit\u00e0 di prenotazione telefonica ha facilitato l\u2019iter per i cittadini che hanno cos\u00ec evitato file inutili e pericolo di assembramenti. In nove mesi rilasciate quasi duemila carte d\u2019identit\u00e0<br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE &#8211; Sono oltre duemila le carte d\u2019identit\u00e0 rilasciate da gennaio a settembre dall&#8217;ufficio Anagrafe del Comune di rende. Numeri altissimi in tempi di pandemia. \u201cL&#8217;ufficio ha lavorato alacremente &#8211; ha affermato il sindaco Marcello Manna &#8211; mantenendo sempre alta la qualit\u00e0 dei servizi dedicati ai nostri cittadini. Se si pensa che l\u2019anno scorso siamo arrivati a quattromila documenti consegnati \u2013 ha proseguito il primo cittadino &#8211; si pu\u00f2 facilmente comprendere quanto l&#8217;amministrazione stia operando bene in un settore cos\u00ec importante per la comunit\u00e0\u201d.<\/p>\n<p>Le modalit\u00e0 di prenotazione telefoniche hanno facilitato l\u2019iter per i cittadini che hanno cos\u00ec evitato file inutili e pericolo di assembramenti. <strong>Dalle 12,30 alle 13,30<\/strong> si potr\u00e0 accedere al servizio componendo il numero dedicato <strong>0984-8284242.<\/strong> \u201cRicordiamo comunque ai cittadini \u2013 ha concluso Manna &#8211; che le carte d\u2019identit\u00e0 scadute entro sono valide sino al 31 dicembre 2020 e che \u00e8 al momento in fase di approvazione un\u2019ulteriore proroga al 30 aprile 2021\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La modalit\u00e0 di prenotazione telefonica ha facilitato l\u2019iter per i cittadini che hanno cos\u00ec evitato file inutili e pericolo di assembramenti. In nove mesi rilasciate quasi duemila carte d\u2019identit\u00e0<\/p>\n","protected":false},"author":42,"featured_media":140485,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-140484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/140484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=140484"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/140484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/140485"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=140484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=140484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=140484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}