{"id":140699,"date":"2020-11-23T11:11:20","date_gmt":"2020-11-23T10:11:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/boccia-a-cosenza-cittadini-contestano-inutile-passerella\/"},"modified":"2023-01-16T18:11:04","modified_gmt":"2023-01-16T17:11:04","slug":"382471-boccia-a-cosenza-cittadini-contestano-inutile-passerella","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/382471-boccia-a-cosenza-cittadini-contestano-inutile-passerella\/","title":{"rendered":"Boccia a Cosenza, cittadini contestano &#8220;inutile passerella&#8221;"},"content":{"rendered":"<h4>Nell&#8217;ex scalo merci di Vaglio Lise per l&#8217;apertura dell&#8217;ospedale da campo un gruppo di cittadini ha contestato\u00a0la visita del ministro per gli Affari Regionali Francesco Boccia<\/h4>\n<h4><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; &#8220;<strong>Sanit\u00e0 pubblica per la Calabria<\/strong>&#8221; \u00e8 lo slogan che campeggia sullo striscione esposto da un gruppo di cittadini all&#8217;arrivo del <strong>ministro per gli Affari Regionali e le Autonomie Francesco Boccia<\/strong> nell&#8217;ex area merci dello scalo di Vaglio Lise a Cosenza. Slogan e cori da parte dei\u00a0 \u00a0contestatori che hanno definito la presenza del ministro &#8220;un&#8217;inutile passerella&#8221;.<\/p>\n<p><iframe loading=\"lazy\" title=\"Protesta a Cosenza davanti l&#039;ospedale da campo\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/_R62cxHrk1c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Stamattina, prima dell&#8217;arrivo del ministro, un centinaio di persone si sono riunite di fronte l&#8217;ex scalo di Vaglio Lise per poi spostarsi a Catanzaro, alla Cittadella, dove si terr\u00e0 nel pomeriggio la <strong>conferenza Stato-Regioni<\/strong> presieduta proprio dal ministro Boccia e dal presidente facente funzioni Nino Spirl\u00ec. A Cosenza il ministro Boccia, secondo quanto si apprende, a causa di una tabella di marcia serrata, non ha incontrato nessuno dei contestatori mentre a Catanzaro, pare, <strong>incontrer\u00e0 una delegazione di cittadini<\/strong>, per ascoltare le loro ragioni.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-382476 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/11\/sanit\u00e0-vaglio-lise-2.jpg\" alt=\"\" width=\"693\" height=\"345\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell&#8217;ex scalo merci di Vaglio Lise per l&#8217;apertura dell&#8217;ospedale da campo un gruppo di cittadini ha contestato\u00a0la visita del ministro per gli Affari Regionali Francesco Boccia<\/p>\n","protected":false},"author":58,"featured_media":140700,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-140699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/140699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=140699"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/140699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/140700"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=140699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=140699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=140699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}