{"id":141174,"date":"2020-11-30T15:30:59","date_gmt":"2020-11-30T14:30:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rapporto-arpacal-a-crotone-non-pioveva-cosi-dal-1916\/"},"modified":"2023-01-16T18:11:37","modified_gmt":"2023-01-16T17:11:37","slug":"383767-rapporto-arpacal-a-crotone-non-pioveva-cosi-dal-1916","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/383767-rapporto-arpacal-a-crotone-non-pioveva-cosi-dal-1916\/","title":{"rendered":"Rapporto Arpacal: &#8220;a Crotone non pioveva cos\u00ec dal 1916&#8221;"},"content":{"rendered":"<h4>Rapporto Evento pluviometrico del Multirischi Arpacal: per il territorio della provincia di Crotone si \u00e8 trattato di un evento eccezionale. Basti pensare al dato di pioggia giornaliera relativo alla stazione pluviometrica di Crotone<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CROTONE &#8211; Il Centro Funzionale Multirischi dell&#8217;Arpacal, diretto dall&#8217;Ing. <strong>Eugenio Filice<\/strong>, ha trasmesso alla Protezione Civile Regionale ed all&#8217;Assessore all&#8217;Ambiente della Regione Calabria il rapporto di evento riguardante i <strong>fenomeni meteo-pluviometrici occorsi in Calabria dal 21 al 23 novembre 2020,<\/strong> ai fini della predisposizione del documento tecnico di accompagnamento alla delibera di Giunta Regionale di richiesta al Governo Nazionale del riconoscimento dello stato di calamit\u00e0 naturale.<\/p>\n<p>Attraverso l&#8217;analisi dei dati meteo pluviometrici rilevati dalla rete di monitoraggio dell&#8217;Arpacal, il rapporto dimostra che per il territorio della provincia di Crotone si \u00e8 trattato di un evento eccezionale. Basti pensare al dato di pioggia giornaliera relativo alla stazione pluviometrica di Crotone. Se confrontato con la serie storica dei massimi annuali delle piogge giornaliere, nonostante la consistenza notevole della serie (104 anni di osservazioni), <strong>la precipitazione giornaliera registrata dalla stazione il 21 novembre 2020 risulta la pi\u00f9 alta in assoluto dal 1916<\/strong>, inizio del periodo di osservazione.<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/11840\" target=\"_blank\" rel=\"noopener noreferrer\">LEGGI IL RAPPORTO COMPLETO<\/a><\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rapporto Evento pluviometrico del Multirischi Arpacal: per il territorio della provincia di Crotone si \u00e8 trattato di un evento eccezionale. Basti pensare al dato di pioggia giornaliera relativo alla stazione pluviometrica di Crotone<\/p>\n","protected":false},"author":22,"featured_media":141175,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-141174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=141174"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141175"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=141174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=141174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=141174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}