{"id":141254,"date":"2020-12-01T16:47:23","date_gmt":"2020-12-01T15:47:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/covid-una-videoguida-unical-spiega-quali-test-rilevano-linfezione\/"},"modified":"2023-01-16T18:11:42","modified_gmt":"2023-01-16T17:11:42","slug":"383975-covid-una-videoguida-unical-spiega-quali-test-rilevano-linfezione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/383975-covid-una-videoguida-unical-spiega-quali-test-rilevano-linfezione\/","title":{"rendered":"Covid, una videoguida Unical spiega quali test rilevano l&#8217;infezione"},"content":{"rendered":"<h4>La professoressa Dina Bellizzi, docente di Microbiologia avanzata del Dipartimento di Biologia, Ecologia e Scienze della Terra dell&#8217;Unical, spiega quali sono le principali caratteristiche dei diversi test<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>ARCAVACATA (CS) &#8211; Sono tre i test utilizzati per rilevare l&#8217;infezione da Coronavirus. <strong>L&#8217;unico valido per la diagnosi \u00e8 il tampone molecolare<\/strong>. Ci sono poi i tamponi rapidi antigenici e i test sierologici. Il test molecolare (o PCR),\u00a0 evidenzia la <strong>presenza di materiale genetico (RNA) del virus<\/strong>. Viene eseguito su tampone rino-faringeo; il test antigenico, evidenzia la presenza di componenti del virus. Viene eseguito su tampone rino-faringeo; il test sierologico tradizionale o rapido evidenzia la presenza di anticorpi contro il virus. I test sierologici vengono eseguiti su prelievo venoso e sangue capillare. La professoressa <strong>Dina Bellizzi, <\/strong>docente di Microbiologia avanzata del Dipartimento di Biologia, Ecologia e Scienze della Terra dell&#8217;Unical, descrive<strong> in questo video le principali caratteristiche dei diversi test.<\/strong><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/SxFHbSwq31Q\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h4>Consegna a domicilio dei tesserini universitari<\/h4>\n<p style=\"font-weight: 400;\">Quest\u2019anno, per i noti<strong> motivi di sicurezza sanitaria<\/strong>, una parte dei tesserini universitari non sono stati distribuiti attraverso gli uffici di segreteria. Per questo motivo i Servizi didattici hanno organizzato un <strong>servizio di consegna direttamente a casa degli studenti del primo anno dei Corsi di studi<\/strong>, che non hanno ancora potuto ritirarlo.\u00a0I tesserini saranno inviati nei prossimi giorni con una lettera e poi dovranno essere validati digitalmente.<\/p>\n<p style=\"font-weight: 400;\">Le matricole che ne hanno gi\u00e0 fatto richiesta, <strong>caricando il documento e la propria foto su\u00a0<a href=\"https:\/\/quicosenza.it\/news\/11848\">soscr.unical.it<\/a> <\/strong>, devono solo assicurarsi di aver indicato correttamente su Esse3 il proprio indirizzo di domicilio e attendere l\u2019arrivo della lettera. Chi, invece, non avesse ancora fatto richiesta del tesserino, dovr\u00e0 procedere seguendo le istruzioni indicate su questo\u00a0<a href=\"https:\/\/quicosenza.it\/news\/11849\">LINK<\/a><\/p>\n<p style=\"font-weight: 400;\">Il tesserino che arriver\u00e0 a casa non sar\u00e0 ancora attivo, ma <strong>dovr\u00e0 essere validato prenotando un appuntamento su Teams<\/strong>, seguendo le istruzioni che saranno indicate nella lettera. Per la validazione occorrono: pc con webcam per il collegamento su Teams, il documento di identit\u00e0 precedentemente caricato sul sistema\u00a0<a href=\"https:\/\/quicosenza.it\/news\/11848\">soscr.unical.it<\/a>\u00a0e il tesserino ricevuto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La professoressa Dina Bellizzi, docente di Microbiologia avanzata del Dipartimento di Biologia, Ecologia e Scienze della Terra dell&#8217;Unical, spiega quali sono le principali caratteristiche dei diversi test<\/p>\n","protected":false},"author":58,"featured_media":141255,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-141254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=141254"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141255"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=141254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=141254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=141254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}