{"id":141400,"date":"2020-12-03T15:29:01","date_gmt":"2020-12-03T14:29:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/annunziata-continua-la-sospensione-del-pagamento-strisce-blu-per-gli-operatori-sanitari\/"},"modified":"2023-01-16T18:11:52","modified_gmt":"2023-01-16T17:11:52","slug":"384385-annunziata-continua-la-sospensione-del-pagamento-strisce-blu-per-gli-operatori-sanitari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/384385-annunziata-continua-la-sospensione-del-pagamento-strisce-blu-per-gli-operatori-sanitari\/","title":{"rendered":"Annunziata, continua la sospensione del pagamento &#8220;strisce blu&#8221; per gli operatori sanitari"},"content":{"rendered":"<h4><strong>Il sindaco Occhiuto proroga l&#8217;ordinanza fino al 31 gennaio in prossimit\u00e0 dell&#8217;Ospedale per il personale sanitario in servizio e per i medici di medicina generale esponendo l&#8217;apposito tesserino<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div dir=\"ltr\">\n<p class=\"v1gmail-MsoBodyText\">COSENZA &#8211; Il sindaco Mario Occhiuto, ha prorogato, di concerto con l&#8217;Assessore alla mobilit\u00e0 sostenibile di Palazzo dei Bruzi, Michelangelo Spataro, <strong>fino al prossimo 31 gennaio 2021<\/strong>,l\u2019ordinanza di sospensione temporanea dell\u2019applicazione, in prossimit\u00e0 dell\u2019Ospedale dell\u2019Annunziata di Cosenza, delle tariffe di pagamento della sosta negli stalli blu,<strong> esentando il personale sanitario in servizio al nosocomio cittadino, nonch\u00e9 i medici di medicina generale operanti sul territorio comunale<\/strong>. Il provvedimento attuale, che proroga quello in vigore dal 17 novembre scorso, si \u00e8 reso necessario per dare continuit\u00e0 all\u2019adozione di misure che favoriscano e agevolino il servizio prestato da tutti coloro\u00a0 (personale sanitario in servizio presso l&#8217;Ospedale e medici di medicina generale) che in questo particolare momento di emergenza sanitaria sono chiamati a fronteggiare il diffondersi del coronavirus e ad assistere \u00a0le persone bisognevoli di cure, prodigandosi per tutelare la vita e la salute dei cittadini.<\/p>\n<p class=\"v1gmail-MsoBodyText\">\u00a0Nell\u2019ordinanza del Sindaco Occhiuto si precisa che \u201cper vicinanze dell\u2019Ospedale dell\u2019Annunziata devono intendersi <strong>le strade<\/strong>, <strong>ove sono presenti le strisce blu per la sosta a pagamento, di seguito elencate<\/strong>\u201d:<\/p>\n<p class=\"v1gmail-MsoBodyText\">Viale della Repubblica, limitatamente al tratto compreso tra via Diaz e il Ponte Mancini, via Talarico, via Pola, via Fiume, via Felice Migliori, Via Moncenisio, via Sempione, Piazza Faustino La Verde, via Vittorio Veneto, via Monfalcone, via Gradisca, via Gorizia, via Nicola Parisio, via Dalmazia, via Istria, via Savoia e via R.Cadorna.<\/p>\n<p class=\"v1gmail-MsoBodyText\">Al fine di usufruire della disposta sospensione temporanea delle tariffe, si dovr\u00e0 esporre, in modo chiaro e visibile, sul cruscotto dell\u2019autoveicolo utilizzato, il contrassegno o il<strong> tesserino rilasciato dal proprio Ordine professionale<\/strong> o esporre apposita autodichiarazione, redatta ai sensi del DPR 445\/2000, di appartenenza ad una delle categorie esentate dall\u2019ordinanza, indicando la targa della vettura e il servizio prestato. Il provvedimento ribadisce, inoltre, che resta fermo quanto disposto dal Piano generale della sosta nel quale si prevede che i medici di base, convenzionati con l\u2019Asp di Cosenza, nell\u2019espletamento della loro attivit\u00e0 professionale, riguardo agli assistiti residenti nel Comune di Cosenza, possono richiedere all\u2019Ufficio Trasporti e mobilit\u00e0 del Comune il <strong>\u201cpermesso medici\u201d<\/strong>, per parcheggio gratuito valido per un\u2019ora, all\u2019interno di tutte le zone a pagamento del territorio comunale, secondo le modalit\u00e0 esplicitate nelle disposizioni. La Polizia municipale vigiler\u00e0 circa il rispetto dell\u2019ordinanza del Sindaco.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco Occhiuto proroga l&#8217;ordinanza fino al 31 gennaio in prossimit\u00e0 dell&#8217;Ospedale per il personale sanitario in servizio e per i medici di medicina generale esponendo l&#8217;apposito tesserino<\/p>\n","protected":false},"author":58,"featured_media":141401,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-141400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=141400"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141401"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=141400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=141400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=141400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}