{"id":141489,"date":"2020-12-05T09:30:41","date_gmt":"2020-12-05T08:30:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/attivita-didattiche-allunical-cosa-cambia-dopo-il-nuovo-dpcm\/"},"modified":"2023-01-16T18:11:58","modified_gmt":"2023-01-16T17:11:58","slug":"384627-attivita-didattiche-allunical-cosa-cambia-dopo-il-nuovo-dpcm","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/384627-attivita-didattiche-allunical-cosa-cambia-dopo-il-nuovo-dpcm\/","title":{"rendered":"Attivit\u00e0 didattiche all&#8217;Unical, cosa cambia dopo il nuovo Dpcm"},"content":{"rendered":"<h4>I rettori degli atenei calabresi si sono riuniti ieri pomeriggio per discutere su eventuali cambi degli assetti universitari. Didattica ed esami rimangono a distanza mentre le attivit\u00e0 legate alla ricerca nei laboratori proseguiranno dopo l&#8217;Epifania<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>ARCAVACATA (CS) &#8211; Incontro operativo, ieri pomeriggio, del Coruc (il Comitato regionale di coordinamento delle universit\u00e0 calabresi) per discutere di <strong>eventuali cambi di assetto<\/strong> in seguito al nuovo Dpcm del 3 dicembre ed all\u2019Ordinanza del Ministro della salute del 27 novembre 2020, recanti ulteriori misure di contenimento e di gestione dell\u2019emergenza epidemiologica da Covid-19.<\/p>\n<p>I Rettori degli atenei calabresi, l\u2019assessore Sandra Savaglio, in rappresentanza della Regione e i rappresentanti degli studenti, hanno deciso di concerto di <strong>mantenere sostanzialmente invariate le disposizioni in corso<\/strong>. Il Comitato ha reputato che, dal punto di vista didattico, non sarebbe opportuno cambiare nuovamente le modalit\u00e0 di insegnamento e tornare in presenza a pochi giorni dal termine del semestre, anche considerando che molti studenti fuori sede faranno rientro nelle loro case subito dopo il giorno dell\u2019Immacolata. Nel corso dell\u2019incontro \u00e8 stato pertanto deciso di <strong>mantenere le attuali misure fino a Natale<\/strong>, proponendosi di rivalutare la situazione a ridosso dell\u2019Epifania. Proseguiranno, invece, le attivit\u00e0 legate alla ricerca nei laboratori, sempre nel rispetto delle prescrizioni sanitarie e di sicurezza vigenti.<\/p>\n<p>Inoltre il Coruc, in considerazione del passaggio della Calabria dalla zona rossa alla zona arancione e considerate le gravose attivit\u00e0 necessarie per rispettare le scadenze di fine anno, ha auspicato <strong>un incremento della presenza del personale negli atenei<\/strong>, sempre nel rispetto del limite massimo del 50% prescritto dal Dpcm. In seguito alla riunione, il rettore dell\u2019Universit\u00e0 della Calabria, Nicola Leone, ha firmato il nuovo decreto che rester\u00e0 in vigore, quindi, fino al 6 gennaio 2021.<\/p>\n<p><strong>Lezioni, esami e lauree.<\/strong> Restano, sostanzialmente immutate le disposizioni legate alle attivit\u00e0 didattiche collettive, che continueranno a distanza per tutti gli studenti fino al 6 gennaio, salvo diversa disposizione delle competenti autorit\u00e0 nazionali. Anche gli esami, le sedute di laurea e di dottorato si svolgeranno esclusivamente in modalit\u00e0 telematica. I docenti, per\u00f2, potranno svolgere le lezioni o gli esami anche dalle strutture universitarie, qualora necessitino di utilizzare i supporti tecnologici pi\u00f9 performanti presenti nelle aule.<\/p>\n<p><strong>Laboratori.<\/strong>\u00a0 Le attivit\u00e0 di laboratorio, di tirocinio, di tesi e di ricerca non surrogabili in modalit\u00e0 telematica possono essere svolte in presenza, previa autorizzazione dei direttori di dipartimento.<\/p>\n<p><strong>Biblioteche.<\/strong> Le biblioteche di Ateneo saranno aperte solo per la comunit\u00e0 accademica e limitatamente allo svolgimento dei servizi di prestito e di restituzione dei libri. Sar\u00e0 consentita anche la consultazione dei libri fuori prestito soprattutto per venire incontro alle esigenze di tesisti e dottorandi, al fine di consentire la conclusione del loro iter degli studi. L\u2019accesso sar\u00e0 regolato su prenotazione, secondo le modalit\u00e0 stabilite dalle Biblioteche, in sale dedicate e nel rispetto delle misure di sicurezza previste per il contenimento del Covid-19.<\/p>\n<p><strong>Associazioni, centri comuni e Cus.<\/strong> Resteranno chiuse le sedi delle associazioni studentesche ubicate nell\u2019Ateneo, i centri comuni di ogni tipo, i quartieri e la sede del Cus Cosenza.<\/p>\n<p><strong>Alloggi.<\/strong> Sar\u00e0 vietato rientrare nelle residenze universitarie a quanti non risultino gi\u00e0 stabilmente presenti. Eventuali richieste di rientro saranno considerate solo se motivate dalla necessit\u00e0 di partecipare ad attivit\u00e0 didattiche in presenza.<\/p>\n<p><strong>Segreterie.<\/strong> Rester\u00e0 sospesa l\u2019attivit\u00e0 front-office del personale tecnico-amministrativo. L\u2019erogazione dei relativi servizi si svolger\u00e0 esclusivamente in modalit\u00e0 telematica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I rettori degli atenei calabresi si sono riuniti ieri pomeriggio per discutere su eventuali cambi degli assetti universitari. Didattica ed esami rimangono a distanza mentre le attivit\u00e0 legate alla ricerca nei laboratori proseguiranno dopo l&#8217;Epifania<\/p>\n","protected":false},"author":58,"featured_media":141490,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-141489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=141489"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141489\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141490"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=141489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=141489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=141489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}