{"id":141541,"date":"2020-12-07T08:38:52","date_gmt":"2020-12-07T07:38:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/focolaio-nella-rsa-santa-maria-sindaco-chiede-misure-piu-restrittive\/"},"modified":"2023-01-16T18:12:01","modified_gmt":"2023-01-16T17:12:01","slug":"384785-focolaio-nella-rsa-santa-maria-sindaco-chiede-misure-piu-restrittive","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/384785-focolaio-nella-rsa-santa-maria-sindaco-chiede-misure-piu-restrittive\/","title":{"rendered":"Focolaio nella Rsa &#8220;Santa Maria&#8221;, sindaco chiede misure pi\u00f9 restrittive"},"content":{"rendered":"<h4>A Roccabernarda preoccupa un focolaio nella casa di riposo \u201cSanta Maria\u201d. Il sindaco Nicola Bilotta ha chiesto misure pi\u00f9 restrittive per evitare la diffusione ulteriore del virus<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROCCABERNARDA (KR) &#8211; Il servizio di prevenzione ha comunicato al sindaco Nicola Bilotta gli esiti dei tamponi effettuati nella Casa di Riposo \u201cSanta Maria\u201d dove si registrano 44 nuovi positivi per un totale di 62 contagi tra operatori, ospiti e proprietari della struttura. &#8220;Il momento \u00e8 veramente drammatico &#8211; scrive l&#8217;amministrazione comunale su Facebook &#8211; Stiamo vicini ai titolari della Casa di Riposo e, principalmente, ai pazienti che hanno bisogno di cure ed assistenza in modo continuato&#8221;.<\/p>\n<p>A seguito di una riunione \u00e8 emersa la volont\u00e0 unanime di mettere in campo &#8220;misure il pi\u00f9 possibile restringenti per salvaguardare la salute dei cittadini. Dato molto importante, inoltre, \u00e8 l\u2019aver comunicato al servizio di prevenzione una lista di circa 90 nominativi che hanno avuto contatti diretti con i positivi della struttura&#8221;. Da qui l&#8217;appello ai cittadini di rispettare sempre le disposizioni &#8220;solo cos\u00ec possiamo evitare che la situazione peggiori ancora di pi\u00f9&#8221; concludono dall&#8217;amministrazione comunale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Roccabernarda preoccupa un focolaio nella casa di riposo \u201cSanta Maria\u201d. Il sindaco Nicola Bilotta ha chiesto misure pi\u00f9 restrittive per evitare la diffusione ulteriore del virus<\/p>\n","protected":false},"author":42,"featured_media":141542,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[681],"class_list":["post-141541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=141541"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141542"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=141541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=141541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=141541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}