{"id":141637,"date":"2020-12-10T05:00:17","date_gmt":"2020-12-10T04:00:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/i-vaccini-come-risposta-alla-pandemia-webinar-promosso-da-mondosanita\/"},"modified":"2023-01-16T18:12:07","modified_gmt":"2023-01-16T17:12:07","slug":"384999-i-vaccini-come-risposta-alla-pandemia-webinar-promosso-da-mondosanita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/384999-i-vaccini-come-risposta-alla-pandemia-webinar-promosso-da-mondosanita\/","title":{"rendered":"&#8220;I vaccini come risposta alla pandemia&#8221;, webinar promosso da Mondosanit\u00e0"},"content":{"rendered":"<h4>Numerosi sono i vaccini che hanno raggiunto la fase 3 di sperimentazione e che stanno entrando nell\u2019armamentario terapeutico per sconfiggere o almeno controllare l\u2019infezione da coronavirus<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Domani dalle ore <strong>15:30 alle 17:30<\/strong>, si terr\u00e0 il webinar sul tema <strong>&#8220;I vaccini come risposta alla pandemia Covid 19&#8221;.<\/strong> Oltre ad i vaccini con virus attenuati sono in corso di definizione i <strong>vaccini mRNA<\/strong> con una metodica innovativa che parrebbe accelerare i tempi di produzione e quindi di distribuzione globale. <strong>La sicurezza dei vaccini,<\/strong> certificata dagli enti regolatori continentali e nazionali, \u00e8 a quanto pare<strong> comprovata<\/strong> cos\u00ec come la loro efficacia che in quasi tutti supera il 90% della popolazione vaccinata, ma nonostante le assicurazioni riportate dalle pubblicazioni scientifiche sino ad ora prodotte e dai media, la discussione sulla loro programmazione, sulla loro conservazione, sull\u2019obbligatoriet\u00e0 o meno e sulla necessit\u00e0 di pubblicazione definitiva dei dati<strong> \u00e8 in corso con ripercussioni anche sul mondo scientifico oltre che sul sociale<\/strong>.<\/p>\n<p>La necessit\u00e0 di un fast track per salvare vite umane ed economie nazionali, induce <strong>speranze<\/strong> ma anche qualche <strong>sospetto che va superato con la seriet\u00e0 degli attori in campo<\/strong> e con la trasparenza dei percorsi produttivi e distributivi dei vaccini in questione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-385000 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/12\/webinar-vaccini-.jpg\" alt=\"\" width=\"529\" height=\"293\" title=\"\"><\/p>\n<p>Al webinar parteciper\u00e0 <strong>Lorenzo Wittum<\/strong>, Presidente e Amministratore Delegato AstraZeneca S.p.A., Azienda impegnata nella produzione del vaccino contro il Covid. E ancora Roberto Buzzetti, Epidemiologo Clinico, Bergamo &#8211; Antonio Cascio, Direttore Unit\u00e0 Operativa Malattie Infettive Policlinico P. Giaccone, Palermo &#8211; Giovanni Leoni, Vicepresidente FNOMCeO &#8211; Walter Locatelli, Commissario Straordinario, A.Li.Sa Regione Liguria &#8211; Elena Lomazzi, Avvocato A&amp;A Studio Legale &#8211; Pier Luigi Lopalco, Epidemiologo &#8211; Professore di Igiene e Medicina Preventiva, Assessore Sanit\u00e0 e Benessere Animale Regione Puglia &#8211; Roberto Nisini, Direttore Reparto Immunologia, Dipartimento Malattie Infettive Istituto Superiore di Sanit\u00e0 &#8211; Carlo Federico Perno, Direttore Microbiologia Ospedale Pediatrico Bambino Ges\u00f9 Roma &#8211; Mauro Pistello, Vice Presidente SIM &#8211; Professore di Microbiologia Clinica Dipartimento di Ricerca Traslazionale, Universit\u00e0 di Pisa &#8211; Gianni Rezza, Direttore Generale della Prevenzione Sanitaria Ministero della Salute &#8211; Mauro Ruggeri, Responsabile sede Nazionale SIMG &#8211; Ugo Trama, Responsabile Farmaceutica e Protesica della Regione Campania &#8211; Stefano Vella, Adjunct Professor Global Health, Catholic University of Rome.<\/p>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\">Per iscriversi a webinar <strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/11875\" target=\"_blank\" rel=\"noopener noreferrer\">clicca QUI<\/a><\/span><\/strong><\/h4>\n<h4 style=\"text-align: center;\">Per informazioni sul programma <strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/11876\" target=\"_blank\" rel=\"noopener noreferrer\">clicca QUI<\/a><\/span><\/strong><\/h4>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Numerosi sono i vaccini che hanno raggiunto la fase 3 di sperimentazione e che stanno entrando nell\u2019armamentario terapeutico per sconfiggere o almeno controllare l\u2019infezione da coronavirus<\/p>\n","protected":false},"author":42,"featured_media":141638,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,52],"tags":[],"class_list":["post-141637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=141637"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141638"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=141637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=141637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=141637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}