{"id":141669,"date":"2020-12-09T16:49:14","date_gmt":"2020-12-09T15:49:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/le-scippano-la-borsa-facendola-cadere-a-terra-e-fuggono-arrestati-due-giovani\/"},"modified":"2023-01-16T18:12:10","modified_gmt":"2023-01-16T17:12:10","slug":"385080-le-scippano-la-borsa-facendola-cadere-a-terra-e-fuggono-arrestati-due-giovani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/385080-le-scippano-la-borsa-facendola-cadere-a-terra-e-fuggono-arrestati-due-giovani\/","title":{"rendered":"Le scippano la borsa facendola cadere a terra e fuggono: arrestati due giovani"},"content":{"rendered":"<h4><strong>I due giovani sono stati beccati ancora con la refurtiva.<\/strong> Nel corso della perquisizione personale, i poliziotti hanno rinvenuto inoltre 11,14gr di marijuana nelle disponibilit\u00e0 di uno dei due rapinatori<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Due giovani catanzaresi P.F. di 25 anni e P.C. di 21 anni, sono stati arrestati ieri sera, dagli Agenti della Questura di Catanzaro in quanto ritenuti responsabili di una <strong>rapina ai danni di una donna.<\/strong> L\u2019attivit\u00e0 dei poliziotti \u00e8 scattata in seguito ad una segnalazione che denunciava uno <strong>scippo ai danni di una signora<\/strong> che, a piedi, stava percorrendo Viale Pio X a Catanzaro. Mentre una pattuglia \u00e8 sopraggiunta sul luogo dell\u2019accaduto per prendere contatti con la vittima T.A. , la quale,<strong> strattonata e fatta cadere a terra, aveva subito lo scippo della borsa<\/strong>, con vari oggetti personali all\u2019interno e di una busta che teneva nelle mani, un\u2019altra pattuglia ha messo in moto la caccia ai malfattori.<\/p>\n<p>Grazie ad una seconda segnalazione che aveva denunciato che uno dei rapinatori <strong>si era dato alla fuga a bordo di una Fiat Punto bianca<\/strong> in direzione di Via Giovanni XXIII, gli agenti hanno stretto subito il cerchio e sono riusciti a beccare, con l\u2019ausilio di altra pattuglia intervenuta, <strong>l\u2019auto con i fuggiaschi<\/strong> all\u2019altezza dell\u2019intersezione tra via Gioacchino Da Fiore e Viale de Filippis.<strong> I due giovani sono stati ancora beccati con la refurtiva.<\/strong> Nel corso della perquisizione personale, i poliziotti hanno rinvenuto inoltre 11,14 gr di marijuana nelle disponibilit\u00e0 di uno dei due rapinatori. Una volta arrestati, i due giovani sono stati ristretti presso la Casa Circondariale di Siano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I due giovani sono stati beccati ancora con la refurtiva. Nel corso della perquisizione personale, i poliziotti hanno rinvenuto inoltre 11,14gr di marijuana nelle disponibilit\u00e0 di uno dei due rapinatori<\/p>\n","protected":false},"author":22,"featured_media":141670,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-141669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=141669"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141670"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=141669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=141669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=141669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}