{"id":141695,"date":"2020-12-10T04:33:20","date_gmt":"2020-12-10T03:33:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/occhiuto-denuncia-lex-collaboratore-ciro-per-calunnia-disegno-di-false-accuse\/"},"modified":"2023-01-16T18:12:12","modified_gmt":"2023-01-16T17:12:12","slug":"385136-occhiuto-denuncia-lex-collaboratore-ciro-per-calunnia-disegno-di-false-accuse","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/385136-occhiuto-denuncia-lex-collaboratore-ciro-per-calunnia-disegno-di-false-accuse\/","title":{"rendered":"Occhiuto denuncia l&#8217;ex collaboratore Cir\u00f2 per calunnia: &#8220;disegno di false accuse&#8221;"},"content":{"rendered":"<h4>Mario Occhiuto ha reso noto di aver sporto denuncia per calunnia nei confronti del suo ex collaboratore di segreteria Giuseppe Cir\u00f2: \u201cHo anche denunciato un disegno, costruito su false accuse, volto a mettermi fuori gioco\u201d<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Il Sindaco di Cosenza Mario Occhiuto ha reso noto di aver depositato alla Procura della Repubblica presso il Tribunale di Catanzaro e alla Procura della Repubblica presso il Tribunale di Cosenza una denuncia per calunnia nei confronti <strong>dell&#8217;ex collaboratore della sua segreteria Giuseppe Cir\u00f2<\/strong>.<\/p>\n<p>\u201cHo ritenuto doveroso presentare una nuova denuncia nei confronti dell&#8217;ex collaboratore della mia segreteria \u2013 sottolinea il sindaco Occhiuto \u2013 per nuovi particolari che ho appreso a seguito dell&#8217;avviso di chiusura delle indagini preliminari del procedimento aperto a suo tempo dalla Procura della Repubblica DDA di Catanzaro. Giova ricordare \u2013 afferma ancora Mario Occhiuto \u2013 che gi\u00e0 l&#8217;8 marzo 2017 denunciai il mio ex collaboratore alla Procura della Repubblica presso il Tribunale di Cosenza in quanto quest\u2019ultimo si era reso responsabile di gravissimi reati. Contestualmente al deposito della mia denuncia, revocai, doverosamente, l\u2019incarico fiduciario al mio ex collaboratore. Quando successivamente, verso i primi di novembre del 2018 \u2013 sottolinea ancora il sindaco Occhiuto &#8211; fui convocato dalla <strong>Procura della Repubblica di Cosenza<\/strong> per essere interrogato, quale persona sottoposta ad indagini, in quanto il mio ex collaboratore, mettendo in atto un suo proposito vendicativo, conseguente al suo allontanamento, mi aveva \u201cchiamato in correit\u00e0\u201d, fui ascoltato dai magistrati incaricati delle indagini, offrendo puntuali chiarimenti e indicando precisi riscontri per conclamare l\u2019assoluta calunniosit\u00e0 delle accuse del sig. Cir\u00f2&#8221;.<\/p>\n<p>&#8220;Ho ritenuto, quindi, che il procedimento si sarebbe presto definito, ma cos\u00ec non \u00e8 avvenuto. Quel che mi sorprende e che mi ha indotto a presentare una nuova denuncia per calunnia nei confronti del mio ex collaboratore, \u00e8 l&#8217;aver constatato come sia palese che la sua figura sia stata utilizzata da un esponente politico di parte avversa, peraltro con ruoli e funzioni istituzionali di particolare peso e importanza, per porre in essere un vero e proprio disegno, costruito su false accuse di illeciti a mio carico, finalizzato a mettermi fuori gioco, attraverso la compartecipazione di alcune delle autorit\u00e0 inquirenti compiacenti verso il suddetto esponente. Del disegno in mio danno \u2013 ha aggiunto il sindaco Occhiuto \u2013 ha fatto parte un discutibilissimo e poco ortodosso modus procedendi che ha eletto un falsificatore e calunniatore al rango di testimone attendibile e decisivo per delegittimare la mia azione politica e farmi apparire come soggetto autore di vari reati. In diverse occasioni, nel corso del 2019, il mio ex collaboratore, convocato \u201cper le vie brevi\u201d, \u00e8 stato ascoltato per rendere dichiarazioni utili alle indagini a mio carico, dichiarazioni che sono state da lui integrate anche a seguito di \u201cpresentazioni spontanee\u201d. Ed \u00e8 stato in queste occasioni che il mio ex collaboratore, oltre a millantare conoscenza di fatti a lui, invece, certamente sconosciuti e a sbandierare cognizioni tecniche che certamente non gli appartengono, ha ulteriormente perpetrato il delitto di calunnia nei miei confronti. <strong>La falsit\u00e0 delle accuse \u00e8 immediatamente rilevabile attraverso la completa disamina del materiale investigativo raccolto dal quale emerge anche la contraddittoria ed illogica versione dei fatti<\/strong>&#8220;.<\/p>\n<p>&#8220;Aggiungo che il sig. Cir\u00f2 \u00e8 ben consapevole del suo ruolo di \u201cproduttore\u201d, in tutti i procedimenti connessi alla mia persona, di false accuse a mio carico, al punto da pubblicare su Facebook, sotto il falso nome di Piero Guscepi (anagramma del suo nome e cognome) <strong>diversi \u201cannunci\u201d circa prossime azioni della magistratura nei miei confronti<\/strong>. Tanto \u00e8 vero che questa mattina \u2013 ha aggiunto Occhiuto \u2013 ho integrato la mia ultima denuncia (presentata il 23 e il 24 novembre scorsi) con una nuova denuncia (alla Procura di Catanzaro e alla Procura di Cosenza) nella quale, richiamando le attivit\u00e0 poste in essere dal mio ex collaboratore su Facebook, con il falso profilo di Piero Guscepi, ho segnalato che, pochi giorni dopo il deposito della mia denuncia, a Catanzaro e a Cosenza, la pagina facebook utilizzata in mio danno (quella a nome Piero Guscepi) \u00e8 stata rimossa&#8221;.<\/p>\n<p>&#8220;Tanto \u2013 sottolinea Occhiuto \u2013 non pu\u00f2 essere frutto di mera casualit\u00e0, ma dimostra, senza dubbio, che l&#8217;ex mio collaboratore di segreteria \u00e8 stato informato della mia iniziativa giudiziaria nei suoi confronti. Pertanto, nell&#8217;insistere nella mia denuncia, ho chiesto che vengano svolte le indagini del caso, onde accertare l&#8217;autore o gli autori della indebita rivelazione di fatti coperti dal segreto d&#8217;ufficio. Di tutto questo \u2013 ha concluso il sindaco \u2013 ho <strong>informato pi\u00f9 volte il Presidente della Repubblica Sergio Mattarella<\/strong> e le pi\u00f9 alte cariche dello Stato, dalla Presidente del Senato, Maria Elisabetta Alberti Casellati, al Presidente della Camera Roberto Fico, al Vice Presidente del Consiglio Superiore della Magistratura, sollecitando un loro autorevole intervento. A tutti ho fatto rilevare che \u00e8 inammissibile che, in uno Stato di diritto quale l\u2019Italia, possano accadere simili episodi, senza che si possa correggere il tiro, in base a quel meccanismo di autodifesa e di autorimedio istituzionale che proprio la nostra architettura costituzionale prevede e contempla. Sarebbe veramente una resa per la democrazia non individuare il modo di perseguire condotte non certamente irreprensibili, specie quando, come nel caso di specie, promanano da rappresentanti di istituzioni che dovrebbero essere al di sopra di ogni sospetto\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mario Occhiuto ha reso noto di aver sporto denuncia per calunnia nei confronti del suo ex collaboratore di segreteria Giuseppe Cir\u00f2: \u201cHo anche denunciato un disegno, costruito su false accuse, volto a mettermi fuori gioco\u201d<\/p>\n","protected":false},"author":42,"featured_media":141696,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[19],"class_list":["post-141695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=141695"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141696"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=141695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=141695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=141695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}