{"id":141843,"date":"2020-12-11T17:33:14","date_gmt":"2020-12-11T16:33:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/trebisacce-operai-consorzio-bonifica-in-protesta-senza-stipendio-da-oltre-4-mesi\/"},"modified":"2023-01-16T18:12:23","modified_gmt":"2023-01-16T17:12:23","slug":"385510-trebisacce-operai-consorzio-bonifica-in-protesta-senza-stipendio-da-oltre-4-mesi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/385510-trebisacce-operai-consorzio-bonifica-in-protesta-senza-stipendio-da-oltre-4-mesi\/","title":{"rendered":"Trebisacce, operai Consorzio Bonifica in protesta: senza stipendio da oltre 4 mesi"},"content":{"rendered":"<h4>Circa 20 lavoratori sono saliti sul tetto della centrale idroelettrica, in contrada Insiti a Corigliano-Rossano e stanno protestando da pi\u00f9 di 24 ore<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>TREBISACCE (CS) &#8211; Una ventina di lavoratori del Consorzio di Bonifica di Trebisacce da oltre 24 ore, stanno protestando contro le <strong>promesse non mantenute dall&#8217;Ente consortile.<\/strong> Si tratta di padri di famiglia che sono saliti sul tetto della centrale idroelettrica, in contrada Insiti a Corigliano-Rossano.<strong> I manifestanti chiedono il pagamento di oltre 4 mensilit\u00e0 arretrate<\/strong>. &#8220;Nessun impegno \u00e8 stato mantenuto, &#8211; denunciano i lavoratori &#8211; chiediamo risposte concrete e immediate.&#8221; Sul posto sono presenti anche i referenti sindacali di Cgil-Cisl e Uil e le forze dell&#8217;ordine.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-385514 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/12\/lavoratori-trabisacce.jpg\" alt=\"\" width=\"667\" height=\"500\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-385513 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/12\/trebisacce2.jpg\" alt=\"\" width=\"720\" height=\"500\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Circa 20 lavoratori sono saliti sul tetto della centrale idroelettrica, in contrada Insiti a Corigliano-Rossano e stanno protestando da pi\u00f9 di 24 ore<\/p>\n","protected":false},"author":22,"featured_media":141844,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-141843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=141843"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141844"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=141843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=141843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=141843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}