{"id":141978,"date":"2020-12-19T15:30:10","date_gmt":"2020-12-19T14:30:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scuola-cuzzupi-ugl-fonte-di-sapere-e-non-luogo-di-ansia\/"},"modified":"2023-01-16T18:12:32","modified_gmt":"2023-01-16T17:12:32","slug":"385920-scuola-cuzzupi-ugl-fonte-di-sapere-e-non-luogo-di-ansia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/385920-scuola-cuzzupi-ugl-fonte-di-sapere-e-non-luogo-di-ansia\/","title":{"rendered":"Scuola, Cuzzupi (Ugl): &#8220;fonte di sapere e non luogo di ansia&#8221;"},"content":{"rendered":"<h4>Il segretario nazionale Ugl Scuola, Ornella Cuzzupi: &#8220;la scuola \u00e8 un luogo sicuro, dove s\u2019impara, si socializza, si cresce e ci si forma per affrontare il futuro&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; \u201cOccorre approfittare di questo periodo per predisporre adeguati interventi atti a tutelare il diritto allo studio e al fine di consentire ai nostri giovani la libert\u00e0 di ritornare in classe e vivere appieno la comunit\u00e0 educante con la spensieratezza dei loro anni e con la consapevolezza che l\u00ec <strong>\u00e8 un luogo sicuro, dove s\u2019impara, si socializza, si cresce e ci si forma per affrontare il futuro<\/strong>\u201d. La dichiarazione del Segretario Nazionale Ugl Scuola, <strong>Ornella Cuzzupi<\/strong>, se da un lato \u00e8 un auspicio per il ritorno a una didattica in presenza per tutti gi\u00e0 nei primi giorni del nuovo anno, dall\u2019altro \u00e8 una precisa denuncia dei guasti prodotti da una politica disorganizzata e poco attenta alla realt\u00e0 dei fatti.<\/p>\n<p>\u201cLa nostra Organizzazione ha dal primo momento denunciato le carenze e i rischi che si correvano, arrivando al punto di raccomandare \u2013 come poi \u00e8 avvenuto in gran del Paese e per le classi secondarie \u2013 la chiusura delle scuole a fine precauzionale. Su tale tema \u2013 continua il Segretario Nazionale &#8211; riteniamo del tutto condivisibili le affermazioni del Coordinatore del Comitato Tecnico Scientifico, <strong>Agostino Miozzo<\/strong>, quando dichiara che<strong> laddove dovesse verificarsi il non ritorno a scuola dei ragazzi dopo le festivit\u00e0 sarebbe un fallimento generalizzato della politica<\/strong>\u201d.<\/p>\n<p>Ma, come ha sempre fatto, la Responsabile Scuola dell\u2019Unione Generale del Lavoro, ben delinea il perimetro della questione: \u201cLa sicurezza deve essere per\u00f2 garantita a tutti i protagonisti del mondo scolastico: alunni, docenti, Personale ATA. Questo \u00e8 l\u2019unico modo affinch\u00e9 l\u2019istituzione sia vissuta nel modo giusto e<strong> non come luogo di ansia e di timore.<\/strong> Su questo tema occorre massima fermezza e decisione. Sarebbe una sciagura se il Ministero, come fatto sino ad oggi, continuasse a immaginare e descrivere ci\u00f2 che non c\u2019\u00e8 o, peggio ancora, ad imporre scelte dettate da presupposti politici e non per il bene dell\u2019istituzione. Su questo noi come Federazione Scuola e come UGL vigileremo pronti, come sempre, a denunciare e combattere le anomalie.<strong> La Scuola deve essere intesa come un\u2019entit\u00e0 viva e come tale deve essere salvaguardata e garantita.<\/strong> Per noi questa \u00e8 la regola!\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il segretario nazionale Ugl Scuola, Ornella Cuzzupi: &#8220;la scuola \u00e8 un luogo sicuro, dove s\u2019impara, si socializza, si cresce e ci si forma per affrontare il futuro&#8221;<\/p>\n","protected":false},"author":22,"featured_media":141979,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-141978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=141978"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/141978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141979"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=141978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=141978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=141978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}