{"id":142036,"date":"2020-12-19T10:00:25","date_gmt":"2020-12-19T09:00:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/dattilografia-online-a-frascineto-un-corso-di-formazione-professionale\/"},"modified":"2023-01-16T18:12:37","modified_gmt":"2023-01-16T17:12:37","slug":"386078-dattilografia-online-a-frascineto-un-corso-di-formazione-professionale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/386078-dattilografia-online-a-frascineto-un-corso-di-formazione-professionale\/","title":{"rendered":"Dattilografia online, a Frascineto un corso di formazione professionale"},"content":{"rendered":"<h4>In ambito professionale \u00e8 sempre pi\u00f9 crescente l\u2019importanza e la diffusione e l\u2019interesse dell\u2019utilizzo del computer che richiede un approfondita conoscenza della tastiera e la competenza specifica del scrivere secondo la regola dell\u2019arte<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>FRASCINETO (CS) &#8211; L\u2019Amministrazione Comunale di Frascineto, ha promosso un corso di dattilografia on line, mediante una convenzione con un la Scuola di Formazione Continua di comprovata esperienza. Al superamento dell\u2019esame finale del corso verr\u00e0 rilasciato un \u201cAttestato di Addestramento Professionale\u201d riconosciuto e valido come titolo di riconoscimento anche nelle graduatorie per il personale ATA.<br \/>\n&#8220;In un momento storico cos\u00ec delicato \u2013 ha dichiarato il sindaco Angelo Catapano &#8211; come quello che stiamo vivendo, unitamente alla scuola di formazione mettiamo a disposizione per i cittadini di Frascineto e non solo, la possibilit\u00e0 di ottenere l\u2019attestazione per una opportunit\u00e0 per avere pi\u00f9 occasioni sul mercato del lavoro. Il corso proposto avr\u00e0 modalit\u00e0 e-learning su piattaforma digitale&#8221;. Tutti gli interessati possono presentare richiesta direttamente via online al seguente indirizzo: info@corsiformazionecontinua.it.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In ambito professionale \u00e8 sempre pi\u00f9 crescente l\u2019importanza e la diffusione e l\u2019interesse dell\u2019utilizzo del computer che richiede un approfondita conoscenza della tastiera e la competenza specifica del scrivere secondo la regola dell\u2019arte<\/p>\n","protected":false},"author":56,"featured_media":142037,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-142036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/142036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=142036"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/142036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/142037"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=142036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=142036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=142036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}