{"id":142654,"date":"2020-12-26T15:10:53","date_gmt":"2020-12-26T14:10:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cassano-nella-notte-fiamme-a-due-automobili\/"},"modified":"2023-01-16T18:13:18","modified_gmt":"2023-01-16T17:13:18","slug":"387831-cassano-nella-notte-fiamme-a-due-automobili","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/387831-cassano-nella-notte-fiamme-a-due-automobili\/","title":{"rendered":"Cassano, nella notte fiamme a due automobili"},"content":{"rendered":"<h4>Le autovetture in uso ad un imprenditore commerciale erano parcheggiate all&#8217;interno dell&#8217;azienda<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>CASSANO ALLO IONIO &#8211; Due automobili, parcheggiate l&#8217;una accanto all&#8217;altra, sono state distrutte ieri sera a Cassano allo Ionio da un incendio di cui non si esclude l&#8217;origine dolosa. Sull&#8217;episodio indagano i carabinieri della Tenenza di Cassano. Le due autovetture erano in uso ad un imprenditore commerciale ed erano parcheggiate all&#8217;interno di un&#8217;azienda agricola di Sibari. Sul posto, oltre ai carabinieri della tenenza di Cassano e agli agenti della polizia municipale, sono intervenute due squadre dei vigili del fuoco, una di Castrovillari e l&#8217;altra di Trebisacce, che hanno lavorato alcune ore per aver ragione delle fiamme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le autovetture in uso ad un imprenditore commerciale erano parcheggiate all&#8217;interno dell&#8217;azienda<\/p>\n","protected":false},"author":56,"featured_media":142655,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-142654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/142654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=142654"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/142654\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/142655"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=142654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=142654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=142654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}