{"id":143100,"date":"2021-01-05T12:06:14","date_gmt":"2021-01-05T11:06:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cariati-smantellamento-centro-di-salute-mentale-a-rischio-1700-pazienti\/"},"modified":"2023-01-16T17:25:34","modified_gmt":"2023-01-16T16:25:34","slug":"389130-cariati-smantellamento-centro-di-salute-mentale-a-rischio-1700-pazienti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/389130-cariati-smantellamento-centro-di-salute-mentale-a-rischio-1700-pazienti\/","title":{"rendered":"Cariati: smantellamento Centro di Salute Mentale, a rischio 1700 pazienti"},"content":{"rendered":"<h4>L&#8217;ipotesi di una possibile chiusura del CSM sta circolando nelle ultime ore. Il sindaco: &#8220;\u00e8 assurdo e improponibile&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CARIATI (CS) &#8211; Il sindaco Filomena Greco interviene sull&#8217;ipotesi di smantellare il Centro di Salute Mentale (CSM) di Cariati ritenendola &#8220;assurda ed improponibile, tanto pi\u00f9 che nell\u2019attuale emergenza, che ha esteso smisuratamente la sofferenza psicologica e mentale, si pensa di demolire ulteriormente gli unici e residuali presidi territoriali che si stanno prodigando tra mille difficolt\u00e0 per far fronte alle tante richieste provenienti dal territorio&#8221;.<\/p>\n<p>Secondo quanto riferisce il primo cittadino, l\u2019obiettivo sarebbe &#8220;di supportare attraverso trasferimento di personale il Servizio di Diagnosi e Cura Psichiatrico (SPDC) di Corigliano che ha gi\u00e0 quattro medici su tre posti ricovero (occupati solo da donne di cui uno riservato da pi\u00f9 di un anno alla stessa paziente); che dimostra pertanto di non averne nessun bisogno data l&#8217;esiguit\u00e0 dei ricoveri e la presenza di altri sanitari gi\u00e0 in organico e che, infine, dovrebbe rappresentare, come da linee guida della psichiatria, l&#8217;ultimo approdo del paziente psichiatrico che ha invece tutto il diritto di curarsi a domicilio mantenendo la sua rete familiare e sociale&#8221;.<\/p>\n<p>&#8220;Nello specifico, per quanto riguarda l&#8217;ambito territoriale provinciale (ATP) Ionio Sud \u2013 precisa il sindaco \u2013 sono solo due gli psichiatri che lavorano nei CSM di Rossano e di Cariati. Come \u00e8 noto, il Centro di Salute Mentale \u00e8 privo da pi\u00f9 di due anni di un organico stabile perch\u00e9 non \u00e8 stato sostituito il personale collocato in quiescenza. Secondo l\u2019ipotesi di ri-programmazione diffusa ufficiosamente \u2013 aggiunge \u2013 i due sanitari in questione dovrebbero essere alternativamente spostati dalla loro sede di servizio (CSM Rossano e CSM Cariati) ed utilizzati presso il SPDC di Corigliano. Tradotto \u2013 scandisce il Primo Cittadino \u2013 ci troveremmo di fronte ad un ulteriore smantellamento dei servizi territoriali con grave sofferenza delle zone periferiche gi\u00e0 duramente penalizzate dalla progressiva desertificazione dei servizi di tutela della salute&#8221;.<\/p>\n<p>&#8220;Tanto pi\u00f9 \u2013 prosegue \u2013 se si considera che il <strong>territorio afferente al CSM di Cariati<\/strong> comprende non solo gli utenti di <strong>Crosia, Calopezzati, Pietrapaola, Mandatoriccio, Campana, Terravecchia, Scala Coeli e Bocchigliero ma anche quelli di Crucoli, Cir\u00f2 Marina e Cir\u00f2<\/strong> facendo registrare, negli ultimi tre anni, circa 1700 pazienti in carico con prestazioni che si aggirano all&#8217;incirca a 10000 annue. Nonostante le esigue risorse il CSM continua ad assicurare la cura a pazienti gravi e cronici, prevenendo scompensi e ricoveri e riducendo i Trattamenti Sanitari Obbligatori (TSO), producendo di conseguenza un risparmio economico ingente per l&#8217;Azienda Sanitaria Provinciale (ASP) considerato che <strong>ogni ricovero costa all&#8217;incirca 250 euro al giorno&#8221;.<\/strong><\/p>\n<p>&#8220;Per queste ragioni \u2013 ritiene la Greco \u2013 \u00e8 <strong>assolutamente impensabile<\/strong> che il CSM di Cariati, uno dei primi istituito in Calabria ed il primo in provincia di Cosenza, che sta gi\u00e0 operando quotidianamente con notevolissime difficolt\u00e0 e con un organico stabile costituito da tre operatori (uno psicologo e due infermieri e con il supporto saltuario dei due psichiatri sopradetti) venga ulteriormente penalizzato impedendo di fatto ai medici di continuare la presa in carico dei pazienti. \u00c8\u00a0assurdo \u2013 conclude la Greco \u2013 che non soltanto non vi sia stata ad oggi alcuna risposta da parte del Governo n\u00e9 del Parlamento col Decreto Calabria alle diverse richieste manifestate all\u2019unanimit\u00e0 dai sindaci calabresi; che non sia stata ascoltata da parte del commissario provinciale alla sanit\u00e0 la nostra richiesta di prevedere per il CSM di Cariati la presenza stabile dello psichiatra; che non soltanto non sia ancora stata trovata una soluzione alla necessaria re-immissione dell\u2019Ospedale di Cariati nelle rete regionale, cos\u00ec come invocato da tutti; ma che si continui imperterriti\u00a0 a privare questo territorio perfino dei Centri di Salute Mentale, primo riferimento per persone vulnerabili, fragili, con disagio psichico e spesso con famiglie multiproblematiche alle spalle&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ipotesi di una possibile chiusura del CSM sta circolando nelle ultime ore. Il sindaco: &#8220;\u00e8 assurdo e improponibile&#8221;<\/p>\n","protected":false},"author":42,"featured_media":143101,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-143100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/143100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=143100"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/143100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/143101"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=143100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=143100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=143100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}