{"id":143114,"date":"2021-01-05T17:56:37","date_gmt":"2021-01-05T16:56:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/gli-adolescenti-ai-tempi-del-coronavirus-1-su-2-e-convinto-di-aver-sprecato-un-anno\/"},"modified":"2023-01-16T17:25:35","modified_gmt":"2023-01-16T16:25:35","slug":"389157-gli-adolescenti-ai-tempi-del-coronavirus-1-su-2-e-convinto-di-aver-sprecato-un-anno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/389157-gli-adolescenti-ai-tempi-del-coronavirus-1-su-2-e-convinto-di-aver-sprecato-un-anno\/","title":{"rendered":"Gli adolescenti ai tempi del Coronavirus: 1 su 2 \u00e8 convinto di aver sprecato un anno"},"content":{"rendered":"<h4>\u00c8 il ritratto che emerge da una indagine realizzata da Ipsos per Save The Children su un campione di 1000 studenti dai 14 ai 18 anni che mostrano preoccupazione e stanchezza dettata dall&#8217;emergenza pandemica<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; &#8220;Giovani al tempo del Coronavirus&#8221; \u00e8 il titolo dell&#8217;indagine condotta a Ipsos per Save The Children su un campione di 1000 studenti dai 14 ai 18 anni e dal quale \u00e8 emerso un quadro sconfortante fatto da <strong>adolescenti stanchi (31%), incerti (17%), preoccupati (17%)<\/strong>. Quasi uno su due (il 46%) \u00e8 convinto di aver &#8220;sprecato&#8221; un anno e uno su tre che la propria preparazione scolastica sia peggiorata e nel 35% dei casi devono recuperare pi\u00f9 materie dell&#8217;anno scorso.<\/p>\n<h4>Dispersione scolastica, insoddisfazione e preoccupazione<\/h4>\n<p>Con un rischio sempre pi\u00f9 concreto di dispersione scolastica: il 28% sostiene che dall&#8217;inizio della pandemia almeno un compagno nella propria classe ha <strong>smesso di frequentare la scuola<\/strong>. Tra le cause principali delle assenze durante la Dad la difficolt\u00e0 di connessione e la mancanza di concentrazione. La stima \u00e8 che almeno 34mila studenti delle superiori, a causa delle assenze prolungate, potrebbero trovarsi a <strong>rischio di abbandono scolastico<\/strong>. \u00c8 il ritratto degli adolescenti che hanno vissuto per quasi <strong>un anno costretti a casa lontani dalle aule<\/strong>, impegnati nella Dad, spesso <strong>senza fare sport o altre attivit\u00e0<\/strong>, vedendo poco gli amici e gli amori, che delinea una indagine realizzata da Ipsos per Save The Children su un campione di 1000 studenti dai 14 ai 18 anni dal titolo &#8220;I giovani ai tempi del Coronavirus&#8221;.<\/p>\n<p>I ragazzi &#8211; secondo l&#8217;indagine &#8211; <strong>si sentono esclusi dalle scelte per il contrasto alla diffusione del Covid<\/strong>: il 65% \u00e8 convinto di pagare in prima persona per l&#8217;incapacit\u00e0 degli adulti di gestire la pandemia, il 43% si sente accusato dagli adulti di essere tra i principali diffusori del contagio, mentre il 42% ritiene ingiusto che agli adulti sia permesso di andare al lavoro, quando a loro non \u00e8 permesso di andare a scuola. Quasi un quarto degli adolescenti (23%) dichiara che, in questo anno di pandemia, ha capito che uscire non \u00e8 poi cos\u00ec importante e che si possono mantenere le relazioni anche on line. Di contro, per\u00f2, l&#8217;85% dei ragazzi intervistati afferma invece di aver capito quanto sia importante uscire con gli amici. Tra le &#8220;<strong>privazioni<\/strong>&#8221; che i ragazzi hanno sofferto di pi\u00f9, anche quella di non aver potuto vivere esperienze sentimentali importanti per la loro et\u00e0 (63%).<\/p>\n<h4>Crisi Covid e adolescenti rimasti &#8220;invisibili&#8221;<\/h4>\n<p>Il 69% degli studenti intervistati ha sentito in qualche modo parlare del Next Generation Eu e sperano che attraverso questo Fondo vengano incrementati i finanziamenti per l&#8217;ingresso nel mondo del lavoro dei giovani (30%) o la possibilit\u00e0 di studiare gratuitamente all&#8217;estero (17%) e all&#8217;universit\u00e0 (17%). &#8220;E necessario dedicare le risorse del Next Generation prioritariamente al <strong>futuro dei pi\u00f9 giovani<\/strong>, con un forte e concreto investimento di lungo periodo sull&#8217;infrastruttura educativa &#8211; sostiene Raffaela Milano, Direttrice dei Programmi Italia-Europa di Save the Children &#8211; In questa crisi troppo a lungo gli adolescenti sono rimasti invisibili. E, come dimostra anche il dibattito di queste ore sulla riapertura degli istituti, l&#8217;impatto prodotto su di loro dalla <strong>chiusura delle scuole<\/strong> \u00e8 ancora gravemente sottovalutato&#8221;. Per questo, aggiunge, &#8220;\u00e8 necessario riaprire subito le scuole in sicurezza con un&#8217;offerta educativa potenziata, soprattutto nei territori pi\u00f9 difficili&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 il ritratto che emerge da una indagine realizzata da Ipsos per Save The Children su un campione di 1000 studenti dai 14 ai 18 anni che mostrano preoccupazione e stanchezza dettata dall&#8217;emergenza pandemica<\/p>\n","protected":false},"author":58,"featured_media":143115,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,1],"tags":[],"class_list":["post-143114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","category-senza-categoria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/143114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=143114"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/143114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/143115"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=143114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=143114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=143114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}