{"id":143621,"date":"2021-01-14T17:14:49","date_gmt":"2021-01-14T16:14:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-verso-il-rinvio-delle-elezioni-provinciali\/"},"modified":"2023-01-16T17:26:09","modified_gmt":"2023-01-16T16:26:09","slug":"390387-cosenza-verso-il-rinvio-delle-elezioni-provinciali","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/390387-cosenza-verso-il-rinvio-delle-elezioni-provinciali\/","title":{"rendered":"Cosenza, verso il rinvio delle elezioni provinciali"},"content":{"rendered":"<h4>Il presidente ff della Regione Calabria avrebbe chiesto di spostare la data all&#8217;11 aprile, cancellando quella imminente del 7 febbraio<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COSENZA &#8211; <\/strong>Secondo quanto si apprende il presidente ff della Regione Calabria avrebbe chiesto il rinvio delle <strong>elezioni del Presidente provincia di Cosenza<\/strong> spostando la data dal 7 febbraio <strong>all&#8217;11 aprile 2021<\/strong>.<\/p>\n<p>Il rinvio \u00e8 stato ritenuto opportuno a seguito delle indicazioni contenute nel verbale della riunione del Comitato Tecnico Scientifico del 29 Dicembre 2020 che evidenziavano il rischio derivante dalle procedure di voto in un contesto regionale da tempo classificato a rischio elevato. Un appuntamento elettorale del genere, inoltre, coinvolgerebbe migliaia di cittadini e di conseguenze una\u00a0 frequente mobilit\u00e0 tra i territori che potrebbe avere <strong>gravi ripercussioni sulla situazione epidemiologica regionale<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presidente ff della Regione Calabria avrebbe chiesto di spostare la data all&#8217;11 aprile, cancellando quella imminente del 7 febbraio<\/p>\n","protected":false},"author":58,"featured_media":143622,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,28],"tags":[],"class_list":["post-143621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/143621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=143621"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/143621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/143622"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=143621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=143621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=143621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}