{"id":143663,"date":"2021-01-15T11:57:12","date_gmt":"2021-01-15T10:57:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-dipendenti-siarc-sul-piede-di-guerra\/"},"modified":"2023-01-16T17:26:12","modified_gmt":"2023-01-16T16:26:12","slug":"390481-cosenza-dipendenti-siarc-sul-piede-di-guerra","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/390481-cosenza-dipendenti-siarc-sul-piede-di-guerra\/","title":{"rendered":"Cosenza, dipendenti Siarc sul piede di guerra"},"content":{"rendered":"<h4>I lavoratori avanzano tre mensilit\u00e0 e la tredicesima. Il sindacato Usb Confederazione Cosenza annuncia &#8221; pronti a mettere in campo ogni tipo di azione&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; I dipendenti della Siarc (Societ\u00e0 Industria Alimentari Ristorazioni Collettive), che operano nei settori della ristorazione e nello specifico, nella nostra provincia, gestisce, in appalto, il servizio mensa di alcune scuole elementari di Cosenza e dell&#8217;Ospedale Spoke Paola &#8211; Cetraro, nonostante abbiano puntualmente lavorato non hanno ancora ricevuto le retribuzioni di ottobre, novembre, dicembre e tredicesima 2020. Lo annuncia il sindacato Usb Confederazione Cosenza.<\/p>\n<p>&#8220;Una situazione estremamente preoccupante &#8211; \u00e8 scritto nella nota sindacale &#8211; che sta costringendo i lavoratori e le loro famiglie a fare i salti mortali per sopravvivere. L&#8217;atteggiamento della SIARC \u00e8 grave e non pi\u00f9 accettabile. Il lavoro deve essere pagato, senza se e senza ma. Abbiamo gi\u00e0 provveduto ad informare della drammatica situazione la Prefettura di Cosenza che ha interpellato il Commissario dell&#8217;ASP di Cosenza, relativamente al servizio che viene offerto all&#8217;Ospedale Spoke Paola &#8211; Cetraro. Gli appalti si confermano essere, in questo territorio, strumento per massimizzare i profitti attraverso lo sfruttamento dei lavoratori. Una miniera d&#8217;oro alla quale tutti ambiscono. Notiamo come ancora una volta il controllo da parte del servizio pubblico, sul rispetto degli obblighi delle ditte appaltatrici, \u00e8 nullo. \u00c8 necessario che gi\u00e0 nelle prossime ore i dipendenti ricevano quanto gli spetta. Siamo pronti a mettere in campo ogni tipo di azione sindacale al fine di tutelare il diritto dei lavoratori ad una puntuale retribuzione&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I lavoratori avanzano tre mensilit\u00e0 e la tredicesima. Il sindacato Usb Confederazione Cosenza annuncia &#8221; pronti a mettere in campo ogni tipo di azione&#8221;<\/p>\n","protected":false},"author":56,"featured_media":143664,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-143663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/143663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=143663"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/143663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/143664"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=143663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=143663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=143663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}