{"id":143900,"date":"2021-01-20T09:10:53","date_gmt":"2021-01-20T08:10:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-presidio-dei-lavoratori-siarc-senza-stipendio-da-tre-mesi\/"},"modified":"2023-01-16T17:26:27","modified_gmt":"2023-01-16T16:26:27","slug":"391109-cosenza-presidio-dei-lavoratori-siarc-senza-stipendio-da-tre-mesi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/391109-cosenza-presidio-dei-lavoratori-siarc-senza-stipendio-da-tre-mesi\/","title":{"rendered":"Cosenza: presidio dei lavoratori Siarc, senza stipendio da tre mesi"},"content":{"rendered":"<h4>I dipendenti si sono ritrovati davanti la sede dell&#8217;azienda a Castrolibero per chiedere le retribuzioni di ottobre, novembre, dicembre e tredicesima 2020<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CASROLIBERO &#8211; &#8220;Diritti e dignit\u00e0 per i lavoratori Siarc&#8221;. \u00c8 la frase scritta sullo striscione affisso questa mattina da alcuni lavoratori della Siarc accompagnati dai rappresentanti del sindacato Usb Confederazione Cosenza, davanti la sede dell&#8217;azienda che operano nei settori della ristorazione. Nello specifico, la Siarc gestisce in appalto il servizio mensa di alcune scuole elementari di Cosenza e dell\u2019Ospedale Spoke Paola \u2013 Cetraro. I lavoratori chiedono l&#8217;immediata erogazione degli stipendi di ottobre, novembre, dicembre e la tredicesima 2020.<\/p>\n<p><iframe loading=\"lazy\" title=\"Lavoratori Siarc senza stipendio - Luigi Pontoriero (Usb)\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/7vA2lXogXJM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-391114 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/01\/protesta-lavoratori-siarc-01.jpg\" alt=\"\" width=\"702\" height=\"435\" title=\"\"><\/p>\n<p>&#8220;Una situazione che va avanti dal 2019, con stipendi accumulati e continui ritardi. Per timore di ritorsioni &#8211; ha spiegato Luigi Pontoriero Usb- questi lavoratori hanno atteso e sperato che la situazione si risolvesse in poco tempo, ma non si pu\u00f2 pi\u00f9 andare avanti cos\u00ec e abbiamo deciso di far emergere la problematica. Abbiamo interessato anche l&#8217;Asp, che \u00e8 l&#8217;ente appaltante, per far pagare i dipendenti direttamente come previsto dal codice degli appalti, ma ad oggi non abbiamo avuto risposte. I lavoratori per ora sono in assemblea sindacale&#8221;.<\/p>\n<p>L&#8217;azienda fa sapere che provveder\u00e0 nella prossima settimana sar\u00e0 erogata la mensilit\u00e0 di ottobre 2020 ed entro fine marzo la tredicesima mensilit\u00e0.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-391115 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/01\/protesta-lavoratori-siarc-02.jpg\" alt=\"\" width=\"729\" height=\"449\" title=\"\"><\/p>\n<h5>Foto Francesco Greco<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>I dipendenti si sono ritrovati davanti la sede dell&#8217;azienda a Castrolibero per chiedere le retribuzioni di ottobre, novembre, dicembre e tredicesima 2020<\/p>\n","protected":false},"author":56,"featured_media":143901,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[565,42],"tags":[],"class_list":["post-143900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-castrolibero-montalto","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/143900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=143900"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/143900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/143901"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=143900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=143900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=143900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}