{"id":144071,"date":"2021-01-23T10:37:26","date_gmt":"2021-01-23T09:37:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/basso-profilo-il-consigliere-intercettato-a-talarico-cesa-deve-sistemare-mio-figlio\/"},"modified":"2023-01-16T17:26:38","modified_gmt":"2023-01-16T16:26:38","slug":"391578-basso-profilo-il-consigliere-intercettato-a-talarico-cesa-deve-sistemare-mio-figlio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/391578-basso-profilo-il-consigliere-intercettato-a-talarico-cesa-deve-sistemare-mio-figlio\/","title":{"rendered":"&#8220;Basso profilo&#8221;, il consigliere intercettato a Talarico: &#8220;Cesa deve sistemare mio figlio&#8221;"},"content":{"rendered":"<h4>\u00c9 quello che emerge dalle indagini delle Dda di Catanzaro nella maxi-operazione contro la &#8216;ndrangheta coordinata dal procuratore Nicola Gratteri<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; &#8220;<strong>Fra&#8217;&#8230;ora noi dobbiamo parlare con Cesa, io mi devo risolvere il problema di mio figlio<\/strong> e gliela dobbiamo mettere anche sul piano Fra&#8217; che noi qui dobbiamo tenere un partito, dobbiamo tenere una segreteria&#8230; dobbiamo tenere &#8230;mio figlio \u00e8 disoccupato, io ho un mezzo&#8230;&#8221;. \u00c9 la conversazione intercettata &#8211; agli atti dell&#8217;inchiesta \u201cBasso profilo\u201d &#8211; \u00a0in cui<strong> Tommaso Brutto<\/strong>, <strong>consigliere comunale di Catanzaro<\/strong>, che \u00e9 tra le persone finite ai domiciliari, <strong>si rivolge all&#8217;assessore regionale al Bilancio Franco Talarico<\/strong> <strong>per chiedergli d&#8217;intercedere con Lorenzo Cesa, ex segretario nazionale dell&#8217;Udc,<\/strong> a proposito di una questione riguardante il figlio.<\/p>\n<p>Intanto partono oggi gli<strong> interrogatori di garanzia dell&#8217;<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/12137\" target=\"_blank\" rel=\"noopener noreferrer\">inchiesta &#8220;Basso profilo&#8221;<\/a><\/span><\/strong>, la <strong>maxi-operazione contro la \u2018ndrangheta<\/strong> in cui sono coinvolti esponenti del mondo politico calabrese, imprenditori e professionisti e che ha portato all&#8217;<strong>arresto in carcere di 13 persone e 35 ai domiciliari,<\/strong> mentre nei confronti di altri due indagati \u00e8 stato disposto <strong>un divieto di dimora ed un obbligo di presentazione alla polizia giudiziaria<\/strong>.<\/p>\n<h4>Talarico arrestato di spicco, Cesa indagato<\/h4>\n<p>Centrale, anche per gli sviluppi dell&#8217;indagine della Dia e della Guardia di finanza, coordinate dalla <strong>Dda di Catanzaro<\/strong>, \u00e8 l&#8217;interrogatorio di uno degli arrestati di spicco, l&#8217;assessore regionale al Bilancio Franco Talarico, dell&#8217;Udc, accusato di <strong>associazione per delinquere aggravata dal metodo mafioso e scambio elettorale politico mafioso<\/strong>.<\/p>\n<p>Talarico \u00e9 stato anche presidente del Consiglio regionale della Calabria ed ha un <strong>rapporto di stretta vicinanza con Lorenzo Cesa<\/strong>, indagato nella stessa inchiesta, ma il cui interrogatorio non \u00e8 stato ancora fissato. Cesa, accusato anche lui di associazione per delinquere aggravata dal metodo mafioso, ha chiesto di essere sentito dai magistrati per poter chiarire il pi\u00f9 presto possibile la sua posizione.<strong> Nel frattempo, si \u00e8 dimesso dalla carica di segretario nazionale dell&#8217;Udc<\/strong>.<\/p>\n<h4>Il finanziere in pensione la &#8220;talpa&#8221;<\/h4>\n<p>Un&#8217;altra figura di spicco dell&#8217;inchiesta \u00e9 <strong>Ercole D&#8217;Alessandro<\/strong>, finanziere in pensione, che, secondo quanto \u00e9 emerso, avrebbe gestito una vasta <strong>attivit\u00e0 illegale<\/strong> che va dagli a<strong>ccessi alle banche dati alle notizie confidenziali.<\/strong> Dalle carte della Dda emerge la disinvoltura con la quale D&#8217;Alessandro discute con l&#8217;imprenditore <strong>Antonio Gallo<\/strong>, un altro dei personaggi-chiave, delle indagini che lo riguardano nell&#8217;ambito di un&#8217;iniziativa imprenditoriale da avviare assieme al notaio di Catanzaro<strong> Rocco Guglielmo,<\/strong> accusato di pi\u00f9 ipotesi di trasferimento fraudolento di valori aggravate dal metodo mafioso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 quello che emerge dalle indagini delle Dda di Catanzaro nella maxi-operazione contro la &#8216;ndrangheta coordinata dal procuratore Nicola Gratteri<\/p>\n","protected":false},"author":58,"featured_media":144072,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-144071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144071"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144072"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}