{"id":144107,"date":"2021-01-24T09:30:39","date_gmt":"2021-01-24T08:30:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/corigliano-drogava-unanziana-denunciata-una-badante\/"},"modified":"2023-01-16T17:26:40","modified_gmt":"2023-01-16T16:26:40","slug":"391723-corigliano-drogava-unanziana-denunciata-una-badante","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/391723-corigliano-drogava-unanziana-denunciata-una-badante\/","title":{"rendered":"Corigliano: drogava un&#8217;anziana, denunciata una badante"},"content":{"rendered":"<h4>La donna avrebbe somministrato psicofarmaci ad una 87enne per evitare che potesse \u201cdare fastidio\u201d<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO -ROSSANO (CS) &#8211; I familiari di A.G., una signora ottantasettenne, hanno conferito incarico all\u2019avv. Francesco Nicoletti al fine di redigere e depositare atto di denuncia nei confronti della <strong>badante, che avrebbe somministrato psicofarmaci all\u2019anziana<\/strong> per evitare che potesse \u201cdare fastidio\u201d.<\/p>\n<p>Gravissime le accuse mosse alla donna, che assisteva la signora dal mese di luglio 2020 e che avrebbe dovuto limitarsi a compiere operazioni socioassistenziali di natura non medica, aiutando l\u2019anziana ad alzarsi, a lavarsi e a mangiare, accompagnandola nei gesti di vita quotidiana.<\/p>\n<p><strong>A rendersi conto di ci\u00f2 che invece stava accadendo \u00e8 stata la figlia<\/strong> dell\u2019ottantasettenne, accorgendosi che la badante somministrava alla madre, volontariamente e senza alcuna autorizzazione, per di pi\u00f9 senza alcuna prescrizione medica, psicofarmaci in modo da drogarla, cagionandole cos\u00ec lesioni volontarie. La stessa figlia notava inoltre un graduale <strong>peggioramento delle condizioni di salute della madre<\/strong> successivamente all\u2019arrivo della badante: l\u2019anziana era molto assente, dormiva tutto il giorno e rifiutava il cibo.<\/p>\n<p>Nel mese di agosto, su un tavolo all\u2019interno dell\u2019abitazione dell\u2019anziana, veniva notata la presenza di un flaconcino contenente psicofarmaco e, a richiesta di giustificazione, la badante rispondeva che si trattava di un farmaco da lei utilizzato. Qualche giorno dopo la situazione peggiorava, con la segnalazione di alcuni vicini di casa che riferivano di non vedere pi\u00f9 l\u2019anziana. Giunta sul posto, la figlia trovava<strong> la madre in stato di incoscienza, allettata e addirittura con difficolt\u00e0 ad aprire anche gli occhi.<\/strong> Allarmata per tale situazione veniva immediatamente contattata la badante la quale riferiva che l\u2019anziana stava bene e che non c\u2019era alcun problema. Le condizioni di salute dell\u2019anziana donna non miglioravano neanche la mattina successiva e, pertanto, i familiari si determinavano a contattare la guardia medica di turno che, dopo un\u2019accurata visita, certificava astenia e sonnolenza da circa due settimane con sospetta overdose da psicofarmaci e rimandava al Pronto Soccorso per ulteriori accertamenti cardiologici e neurologici. Nell\u2019immediatezza, la badante chiedeva a tutti i presenti se dai prelievi o dagli accertamenti fosse risultata la somministrazione di farmaci; circostanza che insospettiva ulteriormente i familiari tanto pi\u00f9 che nella borsa della donna era ben visibile il flaconcino di psicofarmaci notato sul tavolo qualche giorno prima. Stante la gravit\u00e0 della situazione e su richiesta di informazioni da parte dei familiari, la badante, alla presenza di tutti, confessava di aver somministrato tutti i giorni, senza alcuna prescrizione medica e senza autorizzazione, all\u2019anziana signora numerose gocce di psicofarmaci per addormentarla, mostrando effettivamente il flaconcino del farmaco che deteneva nella borsa, e giustificava il proprio gesto riferendo che in tal modo l\u2019anziana non dava \u201cfastidio\u201d.<\/p>\n<p>Da qui la decisione dei familiari di adire le vie legali: \u00abAbbiamo conferito mandato al legale Francesco Nicoletti \u2013 dichiarano &#8211; in quanto \u00e8 nostra ferma volont\u00e0 ottenere giustizia affinch\u00e9 tali riprovevoli fatti non accadano mai pi\u00f9 e, per tale motivo, chiederemo non solo una condanna esemplare di colei che ha attentato alla vita della nostra congiunta ma, altres\u00ec, un ingente risarcimento del danno\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La donna avrebbe somministrato psicofarmaci ad una 87enne per evitare che potesse \u201cdare fastidio\u201d<\/p>\n","protected":false},"author":56,"featured_media":144108,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-144107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144107"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144108"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}