{"id":144235,"date":"2021-01-26T18:21:20","date_gmt":"2021-01-26T17:21:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scuole-a-rende-domani-partono-i-test-anti-covid-su-docenti-e-ata\/"},"modified":"2023-01-16T17:26:49","modified_gmt":"2023-01-16T16:26:49","slug":"392061-scuole-a-rende-domani-partono-i-test-anti-covid-su-docenti-e-ata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/392061-scuole-a-rende-domani-partono-i-test-anti-covid-su-docenti-e-ata\/","title":{"rendered":"Scuole a Rende, domani partono i test anti-Covid su docenti e ATA"},"content":{"rendered":"<h4>Il personale effettuer\u00e0 lo screening nei laboratori dell&#8217;Unical. Alla campagna si affiancher\u00e0 anche l&#8217;app &#8220;Smart Campus School Edition&#8221; per il tracciamento dei contagi<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>RENDE &#8211; A Rende dopo aver ultimato la prima fase di screening sui dipendenti delle mense scolastiche domani toccher\u00e0 al <strong>personale docente e ATA degli istituti comprensivi<\/strong> eseguire i <strong>test anti-Covid nei laboratori dell&#8217;Universit\u00e0 della Calabria<\/strong> &#8220;grazie all&#8217;apporto della Protezione civile e dei volontari della Croce Rossa&#8221;, ha affermato il sindaco Marcello Manna.<\/p>\n<h4>&#8220;Capiremo quanti docenti sono a rischio&#8221;<\/h4>\n<div>\n<p>Alla campagna di screening nata dalla collaborazione tra l&#8217;amministrazione comunale, l&#8217;Unical e la task-force covid voluta dal sindaco&#8221; <strong>hanno aderito su un totale di 539 tra docenti e personale ATA afferenti agli \u00a0istituti comprensivi di Rende,<\/strong> solo 294 (poco Pi\u00f9 del 50%) persone. \u00a0Si \u00e8 prospettata l&#8217;idea di unire le risorse presenti su nostro territorio per garantire maggiore sicurezza nelle scuole&#8221;, ha affermato l&#8217;assessora Lisa Sorrentino.<\/p>\n<p>&#8220;In questo senso, l&#8217;azione congiunta degli enti pubblici potrebbe essere di fondamentale apporto anche nella fase di raccolta e interpretazione di dati funzionali a comprendere su larga scala il comportamento di una determinata categoria. <strong>Capire quanto gli insegnanti siano esposti al rischio<\/strong>, e quanti possano essere considerati soggetti fragili, non \u00e8 affatto banale anche in prospettiva di una prossima e auspicabile <strong>campagna vaccinale mirata<\/strong>. In questo modo sarebbe pi\u00f9 facile elaborare modelli e prendere decisioni in merito. Ci\u00f2 premesso \u00e8 indispensabile che ognuno si muova nell&#8217;interesse comune e in tal senso sottoporsi a test \u00e8 il primo fondamentale step&#8221;, ha dichiarato la Sorrentino.<\/p>\n<\/div>\n<h4>Smart Campus School Edition<\/h4>\n<p>Giovanni \u00a0Laboccetta, CTO dello spinoff dell&#8217;Unical DLVSytem srl che insieme agli spinoff \u00a0Cal-Tek e SOMOS hanno realizzato il <strong>sistema Smart Campus,<\/strong>\u00a0ha illustrato &#8211; in un incontro in un municipio &#8211; le funzionalit\u00e0 \u00a0dell&#8217;app Smart Campus, nata all&#8217;interno dell&#8217;ateneo per il<strong> tracciamento dei contagi all&#8217;interno dell&#8217;Universit\u00e0 della Calabria<\/strong>.<\/p>\n<p>&#8220;L&#8217;idea &#8211; ha spiegato Sorrentino- \u00e8 quella di <strong>affiancare alla campagna di screening anche la possibilit\u00e0 di utilizzare l&#8217;app negli istituti scolastici rendesi<\/strong>&#8220;. Oggi, indubbiamente, le scuole e i trasporti sono tra le situazioni pi\u00f9 difficili da gestire dal punto di vista del contenimento del contagio, soprattutto per la mancanza di strumenti di tracciamento efficaci. Per <strong>contrastare il fenomeno e per garantire il tracciamento dei flussi di persone<\/strong> e, pertanto, l&#8217;individuazione di contatti di a<strong>ccertati casi positivi<\/strong>, ad inizio della pandemia, \u00e8 stato sviluppato un concept di piattaforma tecnologica che ha avuto sviluppo nel sistema Smart Campus, impiegato proficuamente presso l&#8217;Universit\u00e0 della Calabria per <strong>garantire la sicurezza<\/strong> della comunit\u00e0 accademica nell&#8217;attuale contesto di emergenza sanitaria. La piattaforma \u00e8 attualmente disponibile in versione web-app e app mobile sugli store Google e Apple&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-382556 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/11\/Smart-campus.jpg\" alt=\"\" width=\"537\" height=\"358\" title=\"\">&#8220;Gli algoritmi di Intelligenza Artificiale che analizzano i dati provenienti dalle diverse fonti, forniscono feedback in tempo reale rispetto a <strong>potenziali situazioni critiche<\/strong> che si verificano negli spazi monitorati e assicurano il <strong>contact tracing<\/strong>, riconosciuto universalmente come strumento fondamentale di sanit\u00e0 pubblica per la prevenzione e il controllo della diffusione delle malattie trasmissibili da persona a persona. La piattaforma &#8211; prosegue Laboccetta &#8211; si \u00e8 evoluta per trovare applicazione anche <strong>in contesti differenti da quelli universitari<\/strong>, con l&#8217;intento di fornire alle strutture aderenti un sistema che consenta la ricostruzione immediata della catena di contagio, le comunicazioni dirette con tutti i soggetti interessati, una maggiore rapidit\u00e0 nella gestione di tutte le procedure di quarantena in caso di soggetti positivi&#8221;, ha affermato Laboccetta.<\/p>\n<p>&#8220;Tra le evoluzioni di Smart Campus, Smart Campus School Edition si caratterizza per la <strong>specifica funzione di contact tracing in ambito scolastico<\/strong>. Le funzionalit\u00e0 presenti in Smart Campus School Edition consentono, infatti, di applicare la piattaforma a vantaggio degli istituti scolastici aumentando il livello di <strong>sicurezza di studenti, docenti e personale amministrativo, tecnico e ausiliario<\/strong>&#8220;, ha concluso Laboccetta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il personale effettuer\u00e0 lo screening nei laboratori dell&#8217;Unical. Alla campagna si affiancher\u00e0 anche l&#8217;app &#8220;Smart Campus School Edition&#8221; per il tracciamento dei contagi<\/p>\n","protected":false},"author":58,"featured_media":144236,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-144235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144235"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144236"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}