{"id":144297,"date":"2021-01-27T18:37:46","date_gmt":"2021-01-27T17:37:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/reati-ambientali-in-calabria-nel-2020-multe-e-sequestri-per-4-milioni\/"},"modified":"2023-01-16T17:26:52","modified_gmt":"2023-01-16T16:26:52","slug":"392216-reati-ambientali-in-calabria-nel-2020-multe-e-sequestri-per-4-milioni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/392216-reati-ambientali-in-calabria-nel-2020-multe-e-sequestri-per-4-milioni\/","title":{"rendered":"Reati ambientali in Calabria, nel 2020 multe e sequestri per 4 milioni"},"content":{"rendered":"<p><strong>Nel bilancio della Forestale emergono numerosissime attivit\u00e0 illegali legate all\u2019inquinamento e al t<\/strong><strong>raffico di rifiuti e particolare attenzione a flora e fauna in via di estinzione<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; Controllare il territorio con l\u2019obbiettivo di prevenire e reprimere gli illeciti ma soprattutto <strong>tutelare il patrimonio ambientale di cui la Calabria e la Sicilia sono esempi di ricchezza<\/strong>. E\u2019 questo il principale obiettivo dei militari a disposizione del Comando Regione Carabinieri Forestale Calabria, che ha competenza su Calabria e Sicilia. Un\u2019azione constante, intensa e ramificata quella dell\u2019Arma Forestale, che si concentra su pi\u00f9 fronti finalizzati alla tutela del patrimonio boschivo, della fauna selvatica, degli animali da affezione, alla repressione dello smaltimento illecito dei rifiuti e dell\u2019inquinamento delle acque, con particolare attenzione alla tutela e sicurezza agro-alimentare.<\/p>\n<h4>Una task force per tutelare la Calabria<\/h4>\n<p>Un presidio del territorio composto da circa <strong>300 uomini e 53 Stazioni in Calabria<\/strong> e 63 unit\u00e0 in Sicilia suddivise nei Centri Anticrimine Natura di Agrigento, Catania e Palermo, che hanno registrato una crescita dell\u2019attivit\u00e0 preventiva rispetto agli anni precedenti ma anche una importante \u201c\u00e8 <strong>fondamentale la collaborazione dei cittadini<\/strong> che identificano i carabinieri della specialit\u00e0 Forestale come custodi e protettori dell\u2019ambiente che ci circonda\u201d, afferma il Comandante della Regione Carabinieri Forestale Calabria, Colonnello Giorgio Maria Borrelli, che plaude al lavoro svolto dai militari sul complesso e vasto territorio calabro-siculo.<\/p>\n<h4>Forestale, il bilancio in Calabria<\/h4>\n<p>Dall\u2019attivit\u00e0 svolta dai Reparti <strong>in Calabria e Sicilia nel corso del 2020<\/strong>, sono 44.346 controlli effettuati, di cui <strong>42.177 in Calabria<\/strong> e 2.169 in Sicilia, le 22.275 persone controllate ed i 6434 veicoli. Controlli questi che hanno generato la denuncia per varie<strong> violazioni ambientali <\/strong>di 1397 persone, 635<strong> sequestri<\/strong>, di<strong> cui 505 in Calabria, e 27 arresti, dei quali 22 effettuati in Calabria<\/strong>.<\/p>\n<p>Gli <strong>illeciti amministrativi<\/strong> riscontrati e sanzionati sono stati 2530, di cui 2295 in Calabria, che hanno portato ad elevare <strong>sanzioni <\/strong>amministrative<strong>, nel solo territorio calabrese, per circa 4.000.000 di euro con 87 sequestri amministrativi e oltre 2500 persone sanzionate.<\/strong><\/p>\n<p>Particolarmente attivi sono stati i Nuclei Investigativi dell\u2019Arma Forestale (NIPAAF), che hanno svolto importanti e complesse attivit\u00e0 di indagine, facendo emergere <strong>numerosissime attivit\u00e0 illegali legate all\u2019inquinamento ambientale e al traffico di rifiuti<\/strong>.<\/p>\n<p>Particolare attenzione i Carabinieri Forestale pongono anche alle specie di <strong>flora e fauna in via di estinzione i<\/strong>l cui commercio internazionale \u00e8 regolato dalla convenzione di Washington e messa in atto dai Nuclei CITES presenti a Reggio Calabria, Palermo e Catania che svolgono un\u2019incessante attivit\u00e0 investigativa e di controllo sia sul territorio che presso gli e<strong>sercizi commerciali, quali negozi di animali ed antiquari<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel bilancio della Forestale emergono numerosissime attivit\u00e0 illegali legate all\u2019inquinamento e al traffico di rifiuti e particolare attenzione a flora e fauna in via di estinzione<\/p>\n","protected":false},"author":58,"featured_media":144298,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-144297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144297"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144298"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}