{"id":144339,"date":"2021-01-30T20:00:07","date_gmt":"2021-01-30T19:00:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/poste-italiane-disponibili-online-i-dati-2019-per-la-richiesta-dellisee\/"},"modified":"2023-01-16T17:26:55","modified_gmt":"2023-01-16T16:26:55","slug":"392331-poste-italiane-disponibili-online-i-dati-2019-per-la-richiesta-dellisee","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/392331-poste-italiane-disponibili-online-i-dati-2019-per-la-richiesta-dellisee\/","title":{"rendered":"Poste Italiane, disponibili online i dati 2019 per la richiesta dell&#8217;Isee"},"content":{"rendered":"<h4>Il documento, che viene emesso su richiesta dell\u2019intestatario, \u00e8 la sintesi dei prodotti in possesso del cliente e riporta <strong>saldo e giacenza media dei conti attivi\/estinti nel corso d\u2019anno 2019<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"v1MsoNormal\">COSENZA &#8211; Da qualche giorno \u00e8 possibile richiedere anche <strong>on-line i dati dei rapporti intercorrenti con Poste Italiane relativi all\u2019anno 2019<\/strong> e necessari per la presentazione dell\u2019<strong>attestazione Isee<\/strong> (Indicatore della situazione economica equivalente). La certificazione sar\u00e0 disponibile in tempo reale; per poterla ottenere sar\u00e0 necessario accedere tramite le proprie credenziali al sito poste.it nella sezione dedicata.<\/p>\n<h4>Saldo e giacenza del 2019<\/h4>\n<p class=\"v1MsoNormal\">Il documento, che viene emesso su richiesta dell\u2019intestatario, \u00e8 la sintesi dei prodotti in possesso del cliente, in particolare riporta <strong>saldo e giacenza media dei conti attivi\/estinti nel corso d\u2019anno 2019<\/strong>, dei libretti di risparmio, dei Buoni Fruttiferi Postali, delle Postepay nominative e delle Carte Enti Previdenziali, il valore nominale dei Fondi di Investimento, la posizione dei Deposito Titoli nonch\u00e9 l\u2019attestazione dei premi versati per Polizze Assicurative ed \u00e8 disponibile al seguente link\u00a0<a href=\"https:\/\/quicosenza.it\/news\/12190\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.poste.it\/prodotti\/rilascio-certificazione-ai-fini-isee.html<\/a><\/p>\n<p class=\"v1MsoNormal\">Tali informazioni sono utili per accedere alle <strong>prestazioni sociali agevolate<\/strong> quali il <strong>bonus beb\u00e8, il bonus elettrico o idrico<\/strong>, l\u2019iscrizione dei figli ai servizi di prima infanzia, i libri di testo gratuiti, gli assegni di maternit\u00e0 e le forme di sostegno al reddito previste dall\u2019attuale normativa.<\/p>\n<p class=\"v1MsoNormal\">\n","protected":false},"excerpt":{"rendered":"<p>Il documento, che viene emesso su richiesta dell\u2019intestatario, \u00e8 la sintesi dei prodotti in possesso del cliente e riporta saldo e giacenza media dei conti attivi\/estinti nel corso d\u2019anno 2019<\/p>\n","protected":false},"author":58,"featured_media":144340,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,28],"tags":[],"class_list":["post-144339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144339"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144340"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}