{"id":144345,"date":"2021-01-28T17:59:09","date_gmt":"2021-01-28T16:59:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sequestro-beni-per-frode-fiscale-ce-anche-il-deputato-m5s-tucci\/"},"modified":"2023-01-16T17:26:56","modified_gmt":"2023-01-16T16:26:56","slug":"392344-sequestro-beni-per-frode-fiscale-ce-anche-il-deputato-m5s-tucci","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/392344-sequestro-beni-per-frode-fiscale-ce-anche-il-deputato-m5s-tucci\/","title":{"rendered":"Sequestro beni per frode fiscale, c&#8217;\u00e8 anche il deputato M5S Tucci"},"content":{"rendered":"<h4>Le accuse sono, a vario titolo, di dichiarazione fraudolenta mediante l&#8217;utilizzo di fatture per operazioni inesistenti e emissione di fatture per operazioni inesistenti<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>VIBO VALENTIA &#8211; <strong>C&#8217;\u00e8 anche il deputato del M5s, Riccardo Tucc<\/strong>i, tra le persone destinatarie del decreto di <strong>sequestro preventivo di beni<\/strong> nell&#8217;ambito dell&#8217;indagine della Guardia di finanza e coordinata dalla Procura di Vibo Valentia, che ha portato alla denuncia per <strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/12192\" target=\"_blank\" rel=\"noopener noreferrer\">presunta frode di cinque persone<\/a><\/span> e ad un sequestro preventivo di beni per oltre 800 mila euro<\/strong>. Le accuse sono, a vario titolo, di dichiarazione fraudolenta mediante l&#8217;utilizzo di fatture per operazioni inesistenti e emissione di fatture per operazioni inesistenti.<\/p>\n<p>A rendere nota la circostanza che lo riguarda \u00e8 stato lo stesso parlamentare pentastellato.&#8221;La Guardia di Finanza di Vibo Valentia, stamattina &#8211; ha dichiarato &#8211; mi ha <strong>notificato un decreto di sequestro preventivo di beni<\/strong>, per un procedimento penale a carico dell&#8217;azienda e del relativo titolare per cui lavoravo. I fatti contestati sono precedenti all&#8217;inizio della mia attivit\u00e0 politica. Ho gi\u00e0 avvisato di quanto successo i vertici del MoVimento 5 Stelle, il comitato di garanzia e il collegio dei probiviri. Ho piena fiducia nella magistratura e <strong>sono sicuro di poter dimostrare la mia totale estraneit\u00e0 ai fatti contestati<\/strong>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le accuse sono, a vario titolo, di dichiarazione fraudolenta mediante l&#8217;utilizzo di fatture per operazioni inesistenti e emissione di fatture per operazioni inesistenti<\/p>\n","protected":false},"author":58,"featured_media":144346,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-144345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144345"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144346"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}