{"id":144383,"date":"2021-01-29T12:29:49","date_gmt":"2021-01-29T11:29:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/corigliano-lite-tra-conviventi-interviene-il-vicino-con-la-pistola\/"},"modified":"2023-01-16T17:26:59","modified_gmt":"2023-01-16T16:26:59","slug":"392438-corigliano-lite-tra-conviventi-interviene-il-vicino-con-la-pistola","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/392438-corigliano-lite-tra-conviventi-interviene-il-vicino-con-la-pistola\/","title":{"rendered":"Corigliano: lite tra conviventi, interviene il vicino con la pistola"},"content":{"rendered":"<h4>Entrambi gli uomini sono stati denunciati alla Procura della Repubblica di Castrovillari. Uno \u00e8 accusato di minaccia aggravata e percosse, mentre l&#8217;altro di minaccia aggravata<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO CALABRO (CS) \u2013 La vicenda \u00e8 avvenuta questa mattina in un&#8217;abitazione in localit\u00e0 Scalo. Secondo quanto ricostruito dai carabinieri, un uomo, armato di pistola, \u00e8 entrato in casa di una coppia perch\u00e8 attirato dalle urla della donna e tentare di allontanare il marito senegalese, che a sua volta ha utilizzato un coltello da cucina per difendersi. Intervenuti sul posto i militari hanno riportato la calma fra le parti, ma nel corso dei controlli, in entrambi gli appartamenti, hanno sequestrato\u00a0 il coltello usato dal senegalese per minacciare il 41enne italiano, mentre nell\u2019appartamento di quest\u2019ultimo, \u00e8 stata trovata una pistola a salve con tappo rosso e relativo munizionamento, utilizzata contro l\u2019extracomunitario. In caserma, inoltre, la donna ha denunciato il compagno senegalese per percosse. Entrambi gli uomini sono stati denunciati alla Procura della Repubblica di Castrovillari, il senegalese\u00a0 per minaccia aggravata e percosse, mentre il 41enne italiano per minaccia aggravata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrambi gli uomini sono stati denunciati alla Procura della Repubblica di Castrovillari. Uno \u00e8 accusato di minaccia aggravata e percosse, mentre l&#8217;altro di minaccia aggravata<\/p>\n","protected":false},"author":56,"featured_media":144384,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-144383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144383"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144384"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}