{"id":144530,"date":"2021-02-01T18:44:06","date_gmt":"2021-02-01T17:44:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/da-picciotto-a-giovane-boss-di-ndrangheta-il-pentito-in-rinascita-scott-nato-tra-odio-e-faide\/"},"modified":"2023-01-16T17:27:08","modified_gmt":"2023-01-16T16:27:08","slug":"392926-da-picciotto-a-giovane-boss-di-ndrangheta-il-pentito-in-rinascita-scott-nato-tra-odio-e-faide","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/392926-da-picciotto-a-giovane-boss-di-ndrangheta-il-pentito-in-rinascita-scott-nato-tra-odio-e-faide\/","title":{"rendered":"Da picciotto a giovane boss di &#8216;ndrangheta, il pentito in Rinascita-Scott &#8220;nato tra odio e faide&#8221;"},"content":{"rendered":"<h4>Si sono svolti oggi i <strong>primi interrogatori<\/strong> nel corso dell&#8217;udienza del <strong>processo &#8220;Rinascita-Scott&#8221;<\/strong> nell&#8217;aula bunker di Lamezia Terme con l&#8217;interrogatorio del collaboratore di giustizia Luigi Bonaventura<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME (CS) &#8211; Si sono svolti oggi i <strong>primi interrogatori<\/strong> nel corso dell&#8217;udienza del del <strong>processo &#8220;Rinascita-Scott&#8221;<\/strong> nell&#8217;aula bunker di Lamezia Terme. Ad emergere \u00e8 la compattezza dei legami di &#8216;ndrangheta in cui i soggetti sono impregnati dalla cultura dominante.<\/p>\n<p>A rispondere alle domande del sostituto procuratore della Dda di Catanzaro, Annamaria Fristaci, tra gli altri, il collaboratore di giustizia <strong>Luigi Bonaventura, 49<\/strong> anni, in passato <strong>elemento di spicco della famiglia Vrenna-Bonaventura di Crotone<\/strong>. Bonaventura ha raccontato di avere cominciato a fare parte della &#8216;ndrangheta appena nato, con la dote di giovane d&#8217;onore per diritto di successione e poi battezzato <strong>picciotto d&#8217;onore, camorrista di ferro e di sangue<\/strong> (perch\u00e9 aveva commesso degli omicidi), sgarrista.<\/p>\n<h4>Bonaventura, boss &#8220;imbevuto di cultura mafiosa&#8221;<\/h4>\n<p>&#8220;Dovevo prendere la &#8216;santa&#8217; &#8211; ha detto Bonaventura &#8211; ma <strong>nel 2005 mi sono dissociato<\/strong> e il 26 febbraio 2007 ho iniziato a collaborare con la giustizia, da libero e senza alcuna condanna&#8221;. Nipote di Luigi Vrenna, detto &#8220;<strong>U zirru<\/strong>&#8220;, lo zio Giovanni Bonaventura &#8220;<strong>\u00e8 stato come un padre per me<\/strong>&#8221; perch\u00e9 con lui ha condiviso un periodo di guerra di mafia. Luigi Bonaventura ha raccontato di essere diventato <strong>boss, giovanissimo, a 30 anni<\/strong>, perch\u00e9 agli inizi degli anni 2000 lo zio, malato terminale, lo aveva designato a capo della consorteria. Ha riferito di essersi macchiato dei reati di omicidio, estorsione, rapina, narcotraffico.<\/p>\n<p>&#8220;All&#8217;inizio, quando ho deciso di collaborare con la giustizia &#8211; ha detto Bonaventura &#8211; non riuscivo a fare i verbali perch\u00e9 non riuscivo a fare i nomi delle persone che dovevo accusare&#8221;. Ero &#8220;figlio di mamma &#8216;ndrangheta&#8221;, spiega, <strong>imbevuto di cultura mafiosa<\/strong> e con gli occhi e i ricordi imbevuti di una cultura di odio e faide tra famiglie&#8221;. Come la faida che la sua famiglia aveva instaurato con i Feudale.<\/p>\n<p>Secondo Bonaventura, &#8220;il <strong>Crimine \u00e8 il custode delle regole di &#8216;ndrangheta<\/strong>. Il Crimine camminava, si spostava&#8221; perch\u00e9 nel corso degli eventi cambiavano i vertici delle &#8216;ndrangheta e cambiava la localit\u00e0 nella quale si trovava la carica di Crimine. La cosca Vrenna-Bonaventura, ha riferito il collaboratore di giustizia, \u00e8 stata autorizzata da parte dei <strong>De Stefano di Reggio Calabria<\/strong>. Negli anni &#8217;60, il Crimine lo aveva il nonno Luigi Vrenna. La cosca Vrenna-Bonaventura aveva rapporti anche con le cosche reggine come i De Stefano e i Tripodi, tanto che Domenico Tripodi venne coperto a Crotone durante un periodo di latitanza.<\/p>\n<h4>La figura dell&#8217; &#8220;invisibile&#8221;<\/h4>\n<p>Il collaboratore Bonaventura ha parlato anche della figura dell'&#8221;invisibile&#8221;, rappresentato dall&#8217;asso di denari coperto dall&#8217;asso di coppe &#8220;<strong>perch\u00e9 deve essere una figura protetta<\/strong>&#8220;. Secondo il collaboratore di giustizia gli invisibili sono &#8220;<strong>tra il mondo delle cosche e altri mondi. Non sono affiliati e devono restare invisibili<\/strong>&#8220;. Una figura nascosta ma utile alla &#8216;ndrangheta, che si mette a disposizione e agisce nell&#8217;ombra. Secondo Luigi Bonaventura, all&#8217;interno della sua consorteria avevano il ruolo di invisibili T<strong>onino Vrenna e Raffaele Vrenna, &#8220;la parte imprenditoriale della famiglia&#8221;<\/strong>.<\/p>\n<p>Tonino Vrenna, spiega Bonaventura, era figlio del capocosca Luigi Vrenna, &#8220;U zirru&#8221;, nato fuori dal matrimonio, da colei cio\u00e8 che diverr\u00e0 la seconda moglie del boss. Luigi &#8220;U zirru&#8221; decise di chiedere di riconoscere il bambino a un cugino omonimo, Lugi Vrenna, detto &#8220;cap&#8217;i ciucciu&#8221;, padre degli imprenditori Raffaele e Gianni Vrenna. &#8220;Tonino Vrenna era nell&#8217;edilizia &#8211; ricorda il collaboratore &#8211; era <strong>uno che sedeva a capotavola<\/strong> in occasione di cerimonie come matrimoni o altre occasioni&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si sono svolti oggi i primi interrogatori nel corso dell&#8217;udienza del processo &#8220;Rinascita-Scott&#8221; nell&#8217;aula bunker di Lamezia Terme con l&#8217;interrogatorio del collaboratore di giustizia Luigi Bonaventura<\/p>\n","protected":false},"author":58,"featured_media":144531,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-144530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144530"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144531"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}