{"id":144623,"date":"2021-02-03T14:32:55","date_gmt":"2021-02-03T13:32:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-il-trasporto-studenti-e-efficiente-ma-raddoppiare-le-corse-costa\/"},"modified":"2023-01-16T17:27:15","modified_gmt":"2023-01-16T16:27:15","slug":"393175-cosenza-il-trasporto-studenti-e-efficiente-ma-raddoppiare-le-corse-costa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/393175-cosenza-il-trasporto-studenti-e-efficiente-ma-raddoppiare-le-corse-costa\/","title":{"rendered":"Cosenza, trasporto studenti: &#8220;raddoppiare le corse costa&#8221;"},"content":{"rendered":"<h4>Lo riferisce l&#8217;assessore alla mobilit\u00e0 sostenibile Michelangelo Spataro, intervenendo questa mattina alla seduta della Commissione consiliare trasporti sulla problematica del trasporto in sicurezza<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; \u201c<strong>Il servizio di trasporto per gli studenti fornito dall&#8217;Amaco \u00e8 efficace ed efficiente<\/strong>. \u00c8 dal mese di settembre del 2020, in occasione della riapertura delle scuole, che abbiamo messo a punto e concretizzato un <strong>piano di trasporti<\/strong> che consentisse di garantire il servizio di trasporto pubblico locale per gli studenti, in condizioni di sicurezza, ricorrendo al<strong> raddoppio delle corse<\/strong>, in coincidenza con gli orari di ingresso e di uscita dalla scuola\u201d. Lo ha affermato l&#8217;Assessore alla mobilit\u00e0 sostenibile di Palazzo dei Bruzi, Michelangelo Spataro, intervenendo questa mattina alla seduta della <strong>Commissione consiliare trasporti,<\/strong> con all&#8217;ordine del giorno proprio la problematica del trasporto in sicurezza degli studenti, molti dei quali affluiscono nelle scuole cittadine da tutta la provincia.<\/p>\n<p>L&#8217;Assessore Spataro ha fornito una precisazione in ordine alle affermazioni rese qualche giorno fa in Commissione cultura dal dirigente scolastico del Liceo Classico \u201cTelesio\u201d, <strong>Antonio Iaconianni, che aveva sottolineato la presenza solo di qualche corsa in pi\u00f9<\/strong>, ma non del raddoppio delle linee negli orari di ingresso e di uscita dalla scuola.<\/p>\n<h4>Spataro: &#8220;corse gi\u00e0 raddoppiate, ulteriori mezzi \u00e8 un costo&#8221;<\/h4>\n<p>\u201cLe corse sono una dietro l&#8217;altra \u2013 ha puntualizzato l&#8217;Assessore Spataro \u2013 e il servizio \u00e8 sempre garantito. Non vorrei \u2013 ha detto ancora Spataro \u2013 che siano i ragazzi o i genitori ad essere frenati dalla paura del contagio e a non utilizzare i mezzi pubblici. In ogni caso \u2013 ha aggiunto l&#8217;Assessore \u2013 i nostri vettori sono perfettamente in linea con le disposizioni contenute nei diversi DPCM emanati dal governo, con assolute garanzie di sanificazione e igienizzazione giornaliera. Allestire ulteriori mezzi non \u00e8 stato, inoltre, possibile, in quanto <strong>non si sono potuti sostenere costi aggiuntivi, a causa del mancato arrivo dei ristori previsti<\/strong>\u201d.<\/p>\n<p>In linea con quanto affermato dall&#8217;Assessore Spataro, si \u00e8 detto anche il Presidente della Commissione trasporti Gisberto Spadafora che ha accertato, attraverso l&#8217;Amaco, rappresentata alla seduta dell&#8217;organismo consiliare dal Direttore tecnico, Ing.Ernesto Ferraro, che <strong>le corse sono affettivamente raddoppiate<\/strong> negli orari di ingresso ed uscita dalle scuole, contraddicendo di fatto le affermazioni del preside del Liceo \u201cTelesio\u201d Iaconianni.<\/p>\n<p>Spadafora ha ribadito, inoltre, che \u201csono state p<strong>ienamente rispettate le direttive della Prefettura<\/strong>, esplicitate al tavolo tecnico riunitosi pi\u00f9 volte, e che, a differenza di aziende provinciali che fanno fatica a garantire il servizio, <strong>l&#8217;Amaco<\/strong>, sia pure con sforzi incredibili, <strong>riesce a soddisfare le richieste che provengono dalle scuole.<\/strong> Questo \u00e8 frutto di impegno e competenza di cui prendiamo atto con soddisfazione \u2013 ha aggiunto Gisberto Spadafora \u2013 e che apprezziamo ancora di pi\u00f9, attese le difficolt\u00e0 economiche dovute alla mancanza di ristori da parte del governo e considerato anche il parco mezzi limitato e il personale ridotto\u201d.<\/p>\n<h4>Rende: &#8220;puntare anche sul trasporto extraurbano&#8221;<\/h4>\n<p>\u201cIl Comune di Cosenza \u2013 ha sottolineato Bianca Rende \u2013 deve assumere un&#8217;iniziativa politica forte e farsi parte attiva per pretendere, dalla Regione e dai concessionari dei trasporti su linee provinciali, un elevato grado di collaborazione, affinch\u00e9 siano rivisti, con l&#8217;emergenza in corso, i contratti di servizio, assicurando il<strong> raddoppio delle corse nelle tratte utilizzate dalla popolazione scolastica<\/strong>. Senza contare poi \u2013 ha aggiunto Rende \u2013 che la pandemia rappresenta, in questo settore, un&#8217;opportunit\u00e0 per realizzare nuovi investimenti, per <strong>l&#8217;ammodernamento dei mezzi<\/strong> e per l&#8217;avviamento al lavoro di nuovi autisti, in considerazione del fatto che il governo, nel decreto \u201cAgosto\u201d, ha previsto 400 milioni di euro, 100 dei quali riservati al trasporto degli studenti.<\/p>\n<p>&#8220;Sarebbe interessante sapere \u2013 ha aggiunto Bianca Rende \u2013 <strong>se l&#8217;Amministrazione comunale ha rivolto istanza al Governo per avere l&#8217;assegnazione dei fondi<\/strong> che spettano alla citt\u00e0 di Cosenza. Non sarebbe giusto apprendere che i ragazzi non si recano a scuola perch\u00e9 temono la qualit\u00e0 del trasporto locale e che a bordo dei mezzi non sia garantita la sicurezza, a causa del <strong>sovraffollamento<\/strong>. Sar\u00e0, dunque, necessario \u2013 ha concluso Rende \u2013 non cavalcare le paure delle famiglie, ma essere in grado di approntare iniziative per <strong>dare risposte<\/strong> che possano placarle o mitigarle\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo riferisce l&#8217;assessore alla mobilit\u00e0 sostenibile Michelangelo Spataro, intervenendo questa mattina alla seduta della Commissione consiliare trasporti sulla problematica del trasporto in sicurezza<\/p>\n","protected":false},"author":58,"featured_media":144624,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-144623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144623"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144624"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}