{"id":144625,"date":"2021-02-03T15:00:37","date_gmt":"2021-02-03T14:00:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/percettori-del-reddito-nella-rete-del-commerciante-usuraio-arrestato-61enne\/"},"modified":"2023-01-16T17:27:15","modified_gmt":"2023-01-16T16:27:15","slug":"393182-percettori-del-reddito-nella-rete-del-commerciante-usuraio-arrestato-61enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/393182-percettori-del-reddito-nella-rete-del-commerciante-usuraio-arrestato-61enne\/","title":{"rendered":"Percettori del reddito nella rete del commerciante usuraio, arrestato 61enne"},"content":{"rendered":"<h4>L&#8217;uomo &#8211; a cui vengono contestati i <strong>reati di usura e tentata estorsione &#8211; avrebbe prestato soldi a tassi usurari costringendo le vittime a lasciare la loro carta Rdc<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>CUTRO (KR) &#8211; <strong>Avrebbe prestato soldi a tassi usurari a percettori del reddito di cittadinanza<\/strong>, costringendo le proprie vittime a lasciare la loro carta Rdc che utilizzava indebitamente. <strong>Un commerciante A.M., di 61 anni, di Cutro<\/strong>, \u00e8 stato arrestato dai carabinieri in esecuzione di un&#8217;ordinanza di custodia cautelare in carcere emessa dal Gip del Tribunale di Crotone, Michele Ciociola, su richiesta del sostituto procuratore Ines Bellesi. All&#8217;uomo vengono contestati i <strong>reati di usura e tentata estorsione<\/strong>.<\/p>\n<h4>Le vittime percettori di Rdc<\/h4>\n<p>Le indagini, avviate alla fine dello scorso anno e rese pi\u00f9 difficili dal<strong> silenzio delle vittime<\/strong>, hanno portato alla luce un presunto giro di usura nei confronti di percettori dei sussidi statali destinati a chi \u00e8 senza lavoro e senza reddito, che <strong>ruotava intorno all&#8217;esercizio commerciale dell&#8217;arrestato<\/strong>. Secondo quanto emerso A.M., facendo leva sulla gestione della sua attivit\u00e0 commerciale, aveva la possibilit\u00e0 di avvicinare le proprie vittime, le quali, a garanzia di rifondere il credito si trovavano <strong>costrette a consegnare la carta del reddito di cittadinanza<\/strong> al sessantunenne che non si faceva scrupoli di utilizzarla. Le indagini degli investigatori dell&#8217;Arma proseguono perch\u00e9 sarebbero ancora al vaglio le posizioni di <strong>diverse persone incappate nella rete del presunto usuraio<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;uomo &#8211; a cui vengono contestati i reati di usura e tentata estorsione &#8211; avrebbe prestato soldi a tassi usurari costringendo le vittime a lasciare la loro carta Rdc<\/p>\n","protected":false},"author":58,"featured_media":144626,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-144625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144625"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144625\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144626"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}