{"id":144738,"date":"2021-02-05T14:26:39","date_gmt":"2021-02-05T13:26:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rossano-costruzioni-abusive-su-suolo-comunale-denunciato\/"},"modified":"2023-01-16T17:27:22","modified_gmt":"2023-01-16T16:27:22","slug":"393463-rossano-costruzioni-abusive-su-suolo-comunale-denunciato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/393463-rossano-costruzioni-abusive-su-suolo-comunale-denunciato\/","title":{"rendered":"Sequestrate costruzioni abusive a Rossano. Denunciato"},"content":{"rendered":"<h4>I controlli hanno accertato un&#8217;occupazione illecita di due particelle catastali pubbliche di propriet\u00e0 del Comune anche in zona sottoposta a vincolo paesaggistico ambientale<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO-ROSSANO (CS) &#8211; I Carabinieri Forestale di Rossano hanno denunciato un uomo del luogo per <strong>occupazione abusiva di suolo comunale e abusivismo edilizio<\/strong>. Tali reati sono stati contestati a seguito di un controllo effettuato vicino al <strong>Torrente Celadi<\/strong>, nel comune di Corigliano-Rossano area urbana di <strong>Rossano.<\/strong><\/p>\n<p>I carabinieri hanno costatato l\u2019illecita occupazione di <strong>due particelle catastali pubbliche di propriet\u00e0 del Comune di Corigliano-Rossano<\/strong> con realizzazione abusive di opere edili di vario genere e natura. Su suolo comunale, ed in zona sottoposta a vincolo paesaggistico ambientale sono state realizzate infatti opere di natura edile in assenza del permesso a costruire e dell\u2019autorizzazione paesaggistica. In particolare \u00e8 stato realizzato<strong> un muro in cemento armato della lunghezza totale di 24 metri, ed un manufatto\/tettoia<\/strong> con platea in cemento oltre ad aver posto <strong>un cancello che ha ostruito una via comunal<\/strong>e. Si \u00e8 pertanto proceduto al sequestro di una superficie di 310 metri con tutte le opere abusive rinvenute.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I controlli hanno accertato un&#8217;occupazione illecita di due particelle catastali pubbliche di propriet\u00e0 del Comune anche in zona sottoposta a vincolo paesaggistico ambientale<\/p>\n","protected":false},"author":58,"featured_media":144739,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-144738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144738"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144739"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}